{"id":4103,"date":"2023-03-23T10:41:57","date_gmt":"2023-03-23T10:41:57","guid":{"rendered":"https:\/\/dpress.ma\/fr\/?p=4103"},"modified":"2023-03-23T10:41:59","modified_gmt":"2023-03-23T10:41:59","slug":"ramadan-sm-le-roi-recoit-un-message-de-felicitations-du-prince-heritier-de-bahrein","status":"publish","type":"post","link":"https:\/\/dpress.ma\/fr\/2023\/03\/23\/ramadan-sm-le-roi-recoit-un-message-de-felicitations-du-prince-heritier-de-bahrein\/","title":{"rendered":"Ramadan: SM le Roi re\u00e7oit un message de f\u00e9licitations du Prince h\u00e9ritier de Bahre\u00efn"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Dpress<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sa Majest\u00e9 le Roi Mohammed VI a re\u00e7u un message de f\u00e9licitations de SAR le Prince Salman Ben Hamad Al Khalifa, Prince h\u00e9ritier de Bahre\u00efn et pr\u00e9sident du Conseil des ministres, \u00e0 l\u2019occasion de l\u2019av\u00e8nement du mois b\u00e9ni de Ramadan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans ce message, le Prince Salman Ben Hamad Al Khalifa exprime au Souverain ses chaleureuses f\u00e9licitations accompagn\u00e9es de ses sinc\u00e8res v\u0153ux, implorant le Tr\u00e8s-Haut de renouveler pareille occasion pour SM le Roi dans la sant\u00e9 et le bonheur, et pour le Royaume du Maroc fr\u00e8re et la Oumma arabo-islamique dans les bienfaits, la gloire et la prosp\u00e9rit\u00e9.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dpress Sa Majest\u00e9 le Roi Mohammed VI a re\u00e7u un message de f\u00e9licitations de SAR le Prince Salman Ben Hamad Al Khalifa, Prince h\u00e9ritier de Bahre\u00efn et pr\u00e9sident du Conseil des ministres, \u00e0 l\u2019occasion de l\u2019av\u00e8nement du mois b\u00e9ni de Ramadan. Dans ce message, le Prince Salman Ben Hamad Al Khalifa exprime au Souverain ses &hellip;<\/p>\n","protected":false},"author":2,"featured_media":2507,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[],"class_list":["post-4103","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-activites-royales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ramadan: SM le Roi re\u00e7oit un message de f\u00e9licitations du Prince h\u00e9ritier de Bahre\u00efn - Dpress.ma\/fr<\/title>\n<meta name=\"description\" content=\"Sa Majest\u00e9 le Roi Mohammed VI a re\u00e7u un message de f\u00e9licitations de SAR le Prince Salman Ben Hamad Al Khalifa, Prince h\u00e9ritier de Bahre\u00efn et pr\u00e9sident du Conseil des ministres, \u00e0 l\u2019occasion de l\u2019av\u00e8nement du mois b\u00e9ni de Ramadan.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dpress.ma\/fr\/2023\/03\/23\/ramadan-sm-le-roi-recoit-un-message-de-felicitations-du-prince-heritier-de-bahrein\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ramadan: SM le Roi re\u00e7oit un message de f\u00e9licitations du Prince h\u00e9ritier de Bahre\u00efn - Dpress.ma\/fr\" \/>\n<meta property=\"og:description\" content=\"Sa Majest\u00e9 le Roi Mohammed VI a re\u00e7u un message de f\u00e9licitations de SAR le Prince Salman Ben Hamad Al Khalifa, Prince h\u00e9ritier de Bahre\u00efn et pr\u00e9sident du Conseil des ministres, \u00e0 l\u2019occasion de l\u2019av\u00e8nement du mois b\u00e9ni de Ramadan.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dpress.ma\/fr\/2023\/03\/23\/ramadan-sm-le-roi-recoit-un-message-de-felicitations-du-prince-heritier-de-bahrein\/\" \/>\n<meta property=\"og:site_name\" content=\"Dpress.ma\/fr\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-23T10:41:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-23T10:41:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dpress.ma\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/dimensions2-25.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2539\" \/>\n\t<meta property=\"og:image:height\" content=\"1594\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dpress.ma\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dpress.ma\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2023\\\/03\\\/23\\\/ramadan-sm-le-roi-recoit-un-message-de-felicitations-du-prince-heritier-de-bahrein\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2023\\\/03\\\/23\\\/ramadan-sm-le-roi-recoit-un-message-de-felicitations-du-prince-heritier-de-bahrein\\\/\"},\"author\":{\"name\":\"Dpress.ma\",\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/#\\\/schema\\\/person\\\/4898febf3ccd59e6578d838656a306a0\"},\"headline\":\"Ramadan: SM le Roi re\u00e7oit un message de f\u00e9licitations du Prince h\u00e9ritier de Bahre\u00efn\",\"datePublished\":\"2023-03-23T10:41:57+00:00\",\"dateModified\":\"2023-03-23T10:41:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2023\\\/03\\\/23\\\/ramadan-sm-le-roi-recoit-un-message-de-felicitations-du-prince-heritier-de-bahrein\\\/\"},\"wordCount\":131,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2023\\\/03\\\/23\\\/ramadan-sm-le-roi-recoit-un-message-de-felicitations-du-prince-heritier-de-bahrein\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/dimensions2-25.jpg\",\"articleSection\":[\"Activit\u00e9s Royales\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dpress.ma\\\/fr\\\/2023\\\/03\\\/23\\\/ramadan-sm-le-roi-recoit-un-message-de-felicitations-du-prince-heritier-de-bahrein\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2023\\\/03\\\/23\\\/ramadan-sm-le-roi-recoit-un-message-de-felicitations-du-prince-heritier-de-bahrein\\\/\",\"url\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2023\\\/03\\\/23\\\/ramadan-sm-le-roi-recoit-un-message-de-felicitations-du-prince-heritier-de-bahrein\\\/\",\"name\":\"Ramadan: SM le Roi re\u00e7oit un message de f\u00e9licitations du Prince h\u00e9ritier de Bahre\u00efn - Dpress.ma\\\/fr\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2023\\\/03\\\/23\\\/ramadan-sm-le-roi-recoit-un-message-de-felicitations-du-prince-heritier-de-bahrein\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2023\\\/03\\\/23\\\/ramadan-sm-le-roi-recoit-un-message-de-felicitations-du-prince-heritier-de-bahrein\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/dimensions2-25.jpg\",\"datePublished\":\"2023-03-23T10:41:57+00:00\",\"dateModified\":\"2023-03-23T10:41:59+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/#\\\/schema\\\/person\\\/4898febf3ccd59e6578d838656a306a0\"},\"description\":\"Sa Majest\u00e9 le Roi Mohammed VI a re\u00e7u un message de f\u00e9licitations de SAR le Prince Salman Ben Hamad Al Khalifa, Prince h\u00e9ritier de Bahre\u00efn et pr\u00e9sident du Conseil des ministres, \u00e0 l\u2019occasion de l\u2019av\u00e8nement du mois b\u00e9ni de Ramadan.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2023\\\/03\\\/23\\\/ramadan-sm-le-roi-recoit-un-message-de-felicitations-du-prince-heritier-de-bahrein\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dpress.ma\\\/fr\\\/2023\\\/03\\\/23\\\/ramadan-sm-le-roi-recoit-un-message-de-felicitations-du-prince-heritier-de-bahrein\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2023\\\/03\\\/23\\\/ramadan-sm-le-roi-recoit-un-message-de-felicitations-du-prince-heritier-de-bahrein\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/dimensions2-25.jpg\",\"contentUrl\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/dimensions2-25.jpg\",\"width\":2539,\"height\":1594},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2023\\\/03\\\/23\\\/ramadan-sm-le-roi-recoit-un-message-de-felicitations-du-prince-heritier-de-bahrein\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ramadan: SM le Roi re\u00e7oit un message de f\u00e9licitations du Prince h\u00e9ritier de Bahre\u00efn\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/\",\"name\":\"Dpress.ma\\\/fr\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/#\\\/schema\\\/person\\\/4898febf3ccd59e6578d838656a306a0\",\"name\":\"Dpress.ma\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72ecc30e9db047a2e0e7176561eb9d564ed77c8108376495b19bd8336405198a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72ecc30e9db047a2e0e7176561eb9d564ed77c8108376495b19bd8336405198a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72ecc30e9db047a2e0e7176561eb9d564ed77c8108376495b19bd8336405198a?s=96&d=mm&r=g\",\"caption\":\"Dpress.ma\"},\"sameAs\":[\"https:\\\/\\\/www.dpress.ma\"],\"url\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/author\\\/dpress-ma\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ramadan: SM le Roi re\u00e7oit un message de f\u00e9licitations du Prince h\u00e9ritier de Bahre\u00efn - Dpress.ma\/fr","description":"Sa Majest\u00e9 le Roi Mohammed VI a re\u00e7u un message de f\u00e9licitations de SAR le Prince Salman Ben Hamad Al Khalifa, Prince h\u00e9ritier de Bahre\u00efn et pr\u00e9sident du Conseil des ministres, \u00e0 l\u2019occasion de l\u2019av\u00e8nement du mois b\u00e9ni de Ramadan.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dpress.ma\/fr\/2023\/03\/23\/ramadan-sm-le-roi-recoit-un-message-de-felicitations-du-prince-heritier-de-bahrein\/","og_locale":"fr_FR","og_type":"article","og_title":"Ramadan: SM le Roi re\u00e7oit un message de f\u00e9licitations du Prince h\u00e9ritier de Bahre\u00efn - Dpress.ma\/fr","og_description":"Sa Majest\u00e9 le Roi Mohammed VI a re\u00e7u un message de f\u00e9licitations de SAR le Prince Salman Ben Hamad Al Khalifa, Prince h\u00e9ritier de Bahre\u00efn et pr\u00e9sident du Conseil des ministres, \u00e0 l\u2019occasion de l\u2019av\u00e8nement du mois b\u00e9ni de Ramadan.","og_url":"https:\/\/dpress.ma\/fr\/2023\/03\/23\/ramadan-sm-le-roi-recoit-un-message-de-felicitations-du-prince-heritier-de-bahrein\/","og_site_name":"Dpress.ma\/fr","article_published_time":"2023-03-23T10:41:57+00:00","article_modified_time":"2023-03-23T10:41:59+00:00","og_image":[{"width":2539,"height":1594,"url":"https:\/\/dpress.ma\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/dimensions2-25.jpg","type":"image\/jpeg"}],"author":"Dpress.ma","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Dpress.ma","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dpress.ma\/fr\/2023\/03\/23\/ramadan-sm-le-roi-recoit-un-message-de-felicitations-du-prince-heritier-de-bahrein\/#article","isPartOf":{"@id":"https:\/\/dpress.ma\/fr\/2023\/03\/23\/ramadan-sm-le-roi-recoit-un-message-de-felicitations-du-prince-heritier-de-bahrein\/"},"author":{"name":"Dpress.ma","@id":"https:\/\/dpress.ma\/fr\/#\/schema\/person\/4898febf3ccd59e6578d838656a306a0"},"headline":"Ramadan: SM le Roi re\u00e7oit un message de f\u00e9licitations du Prince h\u00e9ritier de Bahre\u00efn","datePublished":"2023-03-23T10:41:57+00:00","dateModified":"2023-03-23T10:41:59+00:00","mainEntityOfPage":{"@id":"https:\/\/dpress.ma\/fr\/2023\/03\/23\/ramadan-sm-le-roi-recoit-un-message-de-felicitations-du-prince-heritier-de-bahrein\/"},"wordCount":131,"commentCount":0,"image":{"@id":"https:\/\/dpress.ma\/fr\/2023\/03\/23\/ramadan-sm-le-roi-recoit-un-message-de-felicitations-du-prince-heritier-de-bahrein\/#primaryimage"},"thumbnailUrl":"https:\/\/dpress.ma\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/dimensions2-25.jpg","articleSection":["Activit\u00e9s Royales"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dpress.ma\/fr\/2023\/03\/23\/ramadan-sm-le-roi-recoit-un-message-de-felicitations-du-prince-heritier-de-bahrein\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dpress.ma\/fr\/2023\/03\/23\/ramadan-sm-le-roi-recoit-un-message-de-felicitations-du-prince-heritier-de-bahrein\/","url":"https:\/\/dpress.ma\/fr\/2023\/03\/23\/ramadan-sm-le-roi-recoit-un-message-de-felicitations-du-prince-heritier-de-bahrein\/","name":"Ramadan: SM le Roi re\u00e7oit un message de f\u00e9licitations du Prince h\u00e9ritier de Bahre\u00efn - Dpress.ma\/fr","isPartOf":{"@id":"https:\/\/dpress.ma\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dpress.ma\/fr\/2023\/03\/23\/ramadan-sm-le-roi-recoit-un-message-de-felicitations-du-prince-heritier-de-bahrein\/#primaryimage"},"image":{"@id":"https:\/\/dpress.ma\/fr\/2023\/03\/23\/ramadan-sm-le-roi-recoit-un-message-de-felicitations-du-prince-heritier-de-bahrein\/#primaryimage"},"thumbnailUrl":"https:\/\/dpress.ma\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/dimensions2-25.jpg","datePublished":"2023-03-23T10:41:57+00:00","dateModified":"2023-03-23T10:41:59+00:00","author":{"@id":"https:\/\/dpress.ma\/fr\/#\/schema\/person\/4898febf3ccd59e6578d838656a306a0"},"description":"Sa Majest\u00e9 le Roi Mohammed VI a re\u00e7u un message de f\u00e9licitations de SAR le Prince Salman Ben Hamad Al Khalifa, Prince h\u00e9ritier de Bahre\u00efn et pr\u00e9sident du Conseil des ministres, \u00e0 l\u2019occasion de l\u2019av\u00e8nement du mois b\u00e9ni de Ramadan.","breadcrumb":{"@id":"https:\/\/dpress.ma\/fr\/2023\/03\/23\/ramadan-sm-le-roi-recoit-un-message-de-felicitations-du-prince-heritier-de-bahrein\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dpress.ma\/fr\/2023\/03\/23\/ramadan-sm-le-roi-recoit-un-message-de-felicitations-du-prince-heritier-de-bahrein\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dpress.ma\/fr\/2023\/03\/23\/ramadan-sm-le-roi-recoit-un-message-de-felicitations-du-prince-heritier-de-bahrein\/#primaryimage","url":"https:\/\/dpress.ma\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/dimensions2-25.jpg","contentUrl":"https:\/\/dpress.ma\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/dimensions2-25.jpg","width":2539,"height":1594},{"@type":"BreadcrumbList","@id":"https:\/\/dpress.ma\/fr\/2023\/03\/23\/ramadan-sm-le-roi-recoit-un-message-de-felicitations-du-prince-heritier-de-bahrein\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dpress.ma\/fr\/"},{"@type":"ListItem","position":2,"name":"Ramadan: SM le Roi re\u00e7oit un message de f\u00e9licitations du Prince h\u00e9ritier de Bahre\u00efn"}]},{"@type":"WebSite","@id":"https:\/\/dpress.ma\/fr\/#website","url":"https:\/\/dpress.ma\/fr\/","name":"Dpress.ma\/fr","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dpress.ma\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/dpress.ma\/fr\/#\/schema\/person\/4898febf3ccd59e6578d838656a306a0","name":"Dpress.ma","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/72ecc30e9db047a2e0e7176561eb9d564ed77c8108376495b19bd8336405198a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/72ecc30e9db047a2e0e7176561eb9d564ed77c8108376495b19bd8336405198a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/72ecc30e9db047a2e0e7176561eb9d564ed77c8108376495b19bd8336405198a?s=96&d=mm&r=g","caption":"Dpress.ma"},"sameAs":["https:\/\/www.dpress.ma"],"url":"https:\/\/dpress.ma\/fr\/author\/dpress-ma\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/posts\/4103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/comments?post=4103"}],"version-history":[{"count":1,"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/posts\/4103\/revisions"}],"predecessor-version":[{"id":4104,"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/posts\/4103\/revisions\/4104"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/media\/2507"}],"wp:attachment":[{"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/media?parent=4103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/categories?post=4103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/tags?post=4103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}