{"id":30747,"date":"2026-05-12T10:29:59","date_gmt":"2026-05-12T10:29:59","guid":{"rendered":"https:\/\/dpress.ma\/fr\/?p=30747"},"modified":"2026-05-12T10:30:01","modified_gmt":"2026-05-12T10:30:01","slug":"previsions-meteorologiques-pour-mardi-12-mai-2026","status":"publish","type":"post","link":"https:\/\/dpress.ma\/fr\/2026\/05\/12\/previsions-meteorologiques-pour-mardi-12-mai-2026\/","title":{"rendered":"Pr\u00e9visions m\u00e9t\u00e9orologiques pour mardi 12 mai 2026"},"content":{"rendered":"\n<p>Dpress<\/p>\n\n\n\n<p>&nbsp;Voici les&nbsp;pr\u00e9visions&nbsp;m\u00e9t\u00e9orologiques pour le mardi 12 mai 2026, \u00e9tablies par la Direction g\u00e9n\u00e9rale de la m\u00e9t\u00e9orologie:<\/p>\n\n\n\n<p>\u2013 Temps assez chaud sur le Sud-est et le Sud.<\/p>\n\n\n\n<p>\u2013 Ond\u00e9es et orages \u00e9pars sur l\u2019extr\u00eame Sud-Est, le Sud de l\u2019Oriental et localement sur les provinces du Sud.<\/p>\n\n\n\n<p>\u2013 Bruine ou gouttes de pluies \u00e9parses sur le Rif, les c\u00f4tes nord et centre et le Moyen Atlas.<\/p>\n\n\n\n<p>\u2013&nbsp;Rafales de vent assez fortes \u00e0 parfois fortes sur le Sud-Est, le Sud de l\u2019Oriental, l\u2019Atlas et le Sud avec chasse-poussi\u00e8res par endroits.<\/p>\n\n\n\n<p>\u2013&nbsp;Temp\u00e9ratures minimales de l\u2019ordre de 04\/10\u00b0C sur l\u2019Atlas et le Rif, de 15\/21\u00b0C sur le Sud de l\u2019Oriental, le Sud-est, l\u2019Est et les provinces sahariennes, et de 10\/15\u00b0C partout ailleurs.<\/p>\n\n\n\n<p>\u2013&nbsp;Temp\u00e9rature maximale en hausse sur le Sud des provinces sahariennes et en baisse ailleurs.<\/p>\n\n\n\n<p>\u2013&nbsp;Mer belle \u00e0 peu agit\u00e9e en M\u00e9diterran\u00e9e et sur le D\u00e9troit, et peu agit\u00e9e \u00e0 agit\u00e9e sur le littoral.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dpress &nbsp;Voici les&nbsp;pr\u00e9visions&nbsp;m\u00e9t\u00e9orologiques pour le mardi 12 mai 2026, \u00e9tablies par la Direction g\u00e9n\u00e9rale de la m\u00e9t\u00e9orologie: \u2013 Temps assez chaud sur le Sud-est et le Sud. \u2013 Ond\u00e9es et orages \u00e9pars sur l\u2019extr\u00eame Sud-Est, le Sud de l\u2019Oriental et localement sur les provinces du Sud. \u2013 Bruine ou gouttes de pluies \u00e9parses sur le &hellip;<\/p>\n","protected":false},"author":2,"featured_media":30629,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[40],"tags":[],"class_list":["post-30747","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-societe-et-regions"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pr\u00e9visions m\u00e9t\u00e9orologiques pour mardi 12 mai 2026 - Dpress.ma\/fr<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dpress.ma\/fr\/2026\/05\/12\/previsions-meteorologiques-pour-mardi-12-mai-2026\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pr\u00e9visions m\u00e9t\u00e9orologiques pour mardi 12 mai 2026 - Dpress.ma\/fr\" \/>\n<meta property=\"og:description\" content=\"Dpress &nbsp;Voici les&nbsp;pr\u00e9visions&nbsp;m\u00e9t\u00e9orologiques pour le mardi 12 mai 2026, \u00e9tablies par la Direction g\u00e9n\u00e9rale de la m\u00e9t\u00e9orologie: \u2013 Temps assez chaud sur le Sud-est et le Sud. \u2013 Ond\u00e9es et orages \u00e9pars sur l\u2019extr\u00eame Sud-Est, le Sud de l\u2019Oriental et localement sur les provinces du Sud. \u2013 Bruine ou gouttes de pluies \u00e9parses sur le &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dpress.ma\/fr\/2026\/05\/12\/previsions-meteorologiques-pour-mardi-12-mai-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Dpress.ma\/fr\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-12T10:29:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T10:30:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dpress.ma\/fr\/wp-content\/uploads\/sites\/2\/2026\/05\/61-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2539\" \/>\n\t<meta property=\"og:image:height\" content=\"1594\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dpress.ma\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dpress.ma\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/12\\\/previsions-meteorologiques-pour-mardi-12-mai-2026\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/12\\\/previsions-meteorologiques-pour-mardi-12-mai-2026\\\/\"},\"author\":{\"name\":\"Dpress.ma\",\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/#\\\/schema\\\/person\\\/4898febf3ccd59e6578d838656a306a0\"},\"headline\":\"Pr\u00e9visions m\u00e9t\u00e9orologiques pour mardi 12 mai 2026\",\"datePublished\":\"2026-05-12T10:29:59+00:00\",\"dateModified\":\"2026-05-12T10:30:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/12\\\/previsions-meteorologiques-pour-mardi-12-mai-2026\\\/\"},\"wordCount\":187,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/12\\\/previsions-meteorologiques-pour-mardi-12-mai-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/05\\\/61-4.jpg\",\"articleSection\":[\"societe et regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/12\\\/previsions-meteorologiques-pour-mardi-12-mai-2026\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/12\\\/previsions-meteorologiques-pour-mardi-12-mai-2026\\\/\",\"url\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/12\\\/previsions-meteorologiques-pour-mardi-12-mai-2026\\\/\",\"name\":\"Pr\u00e9visions m\u00e9t\u00e9orologiques pour mardi 12 mai 2026 - Dpress.ma\\\/fr\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/12\\\/previsions-meteorologiques-pour-mardi-12-mai-2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/12\\\/previsions-meteorologiques-pour-mardi-12-mai-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/05\\\/61-4.jpg\",\"datePublished\":\"2026-05-12T10:29:59+00:00\",\"dateModified\":\"2026-05-12T10:30:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/#\\\/schema\\\/person\\\/4898febf3ccd59e6578d838656a306a0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/12\\\/previsions-meteorologiques-pour-mardi-12-mai-2026\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/12\\\/previsions-meteorologiques-pour-mardi-12-mai-2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/12\\\/previsions-meteorologiques-pour-mardi-12-mai-2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/05\\\/61-4.jpg\",\"contentUrl\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/05\\\/61-4.jpg\",\"width\":2539,\"height\":1594},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/12\\\/previsions-meteorologiques-pour-mardi-12-mai-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pr\u00e9visions m\u00e9t\u00e9orologiques pour mardi 12 mai 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/\",\"name\":\"Dpress.ma\\\/fr\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/#\\\/schema\\\/person\\\/4898febf3ccd59e6578d838656a306a0\",\"name\":\"Dpress.ma\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72ecc30e9db047a2e0e7176561eb9d564ed77c8108376495b19bd8336405198a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72ecc30e9db047a2e0e7176561eb9d564ed77c8108376495b19bd8336405198a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72ecc30e9db047a2e0e7176561eb9d564ed77c8108376495b19bd8336405198a?s=96&d=mm&r=g\",\"caption\":\"Dpress.ma\"},\"sameAs\":[\"https:\\\/\\\/www.dpress.ma\"],\"url\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/author\\\/dpress-ma\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pr\u00e9visions m\u00e9t\u00e9orologiques pour mardi 12 mai 2026 - Dpress.ma\/fr","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dpress.ma\/fr\/2026\/05\/12\/previsions-meteorologiques-pour-mardi-12-mai-2026\/","og_locale":"fr_FR","og_type":"article","og_title":"Pr\u00e9visions m\u00e9t\u00e9orologiques pour mardi 12 mai 2026 - Dpress.ma\/fr","og_description":"Dpress &nbsp;Voici les&nbsp;pr\u00e9visions&nbsp;m\u00e9t\u00e9orologiques pour le mardi 12 mai 2026, \u00e9tablies par la Direction g\u00e9n\u00e9rale de la m\u00e9t\u00e9orologie: \u2013 Temps assez chaud sur le Sud-est et le Sud. \u2013 Ond\u00e9es et orages \u00e9pars sur l\u2019extr\u00eame Sud-Est, le Sud de l\u2019Oriental et localement sur les provinces du Sud. \u2013 Bruine ou gouttes de pluies \u00e9parses sur le &hellip;","og_url":"https:\/\/dpress.ma\/fr\/2026\/05\/12\/previsions-meteorologiques-pour-mardi-12-mai-2026\/","og_site_name":"Dpress.ma\/fr","article_published_time":"2026-05-12T10:29:59+00:00","article_modified_time":"2026-05-12T10:30:01+00:00","og_image":[{"width":2539,"height":1594,"url":"https:\/\/dpress.ma\/fr\/wp-content\/uploads\/sites\/2\/2026\/05\/61-4.jpg","type":"image\/jpeg"}],"author":"Dpress.ma","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Dpress.ma","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dpress.ma\/fr\/2026\/05\/12\/previsions-meteorologiques-pour-mardi-12-mai-2026\/#article","isPartOf":{"@id":"https:\/\/dpress.ma\/fr\/2026\/05\/12\/previsions-meteorologiques-pour-mardi-12-mai-2026\/"},"author":{"name":"Dpress.ma","@id":"https:\/\/dpress.ma\/fr\/#\/schema\/person\/4898febf3ccd59e6578d838656a306a0"},"headline":"Pr\u00e9visions m\u00e9t\u00e9orologiques pour mardi 12 mai 2026","datePublished":"2026-05-12T10:29:59+00:00","dateModified":"2026-05-12T10:30:01+00:00","mainEntityOfPage":{"@id":"https:\/\/dpress.ma\/fr\/2026\/05\/12\/previsions-meteorologiques-pour-mardi-12-mai-2026\/"},"wordCount":187,"commentCount":0,"image":{"@id":"https:\/\/dpress.ma\/fr\/2026\/05\/12\/previsions-meteorologiques-pour-mardi-12-mai-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/dpress.ma\/fr\/wp-content\/uploads\/sites\/2\/2026\/05\/61-4.jpg","articleSection":["societe et regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dpress.ma\/fr\/2026\/05\/12\/previsions-meteorologiques-pour-mardi-12-mai-2026\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dpress.ma\/fr\/2026\/05\/12\/previsions-meteorologiques-pour-mardi-12-mai-2026\/","url":"https:\/\/dpress.ma\/fr\/2026\/05\/12\/previsions-meteorologiques-pour-mardi-12-mai-2026\/","name":"Pr\u00e9visions m\u00e9t\u00e9orologiques pour mardi 12 mai 2026 - Dpress.ma\/fr","isPartOf":{"@id":"https:\/\/dpress.ma\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dpress.ma\/fr\/2026\/05\/12\/previsions-meteorologiques-pour-mardi-12-mai-2026\/#primaryimage"},"image":{"@id":"https:\/\/dpress.ma\/fr\/2026\/05\/12\/previsions-meteorologiques-pour-mardi-12-mai-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/dpress.ma\/fr\/wp-content\/uploads\/sites\/2\/2026\/05\/61-4.jpg","datePublished":"2026-05-12T10:29:59+00:00","dateModified":"2026-05-12T10:30:01+00:00","author":{"@id":"https:\/\/dpress.ma\/fr\/#\/schema\/person\/4898febf3ccd59e6578d838656a306a0"},"breadcrumb":{"@id":"https:\/\/dpress.ma\/fr\/2026\/05\/12\/previsions-meteorologiques-pour-mardi-12-mai-2026\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dpress.ma\/fr\/2026\/05\/12\/previsions-meteorologiques-pour-mardi-12-mai-2026\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dpress.ma\/fr\/2026\/05\/12\/previsions-meteorologiques-pour-mardi-12-mai-2026\/#primaryimage","url":"https:\/\/dpress.ma\/fr\/wp-content\/uploads\/sites\/2\/2026\/05\/61-4.jpg","contentUrl":"https:\/\/dpress.ma\/fr\/wp-content\/uploads\/sites\/2\/2026\/05\/61-4.jpg","width":2539,"height":1594},{"@type":"BreadcrumbList","@id":"https:\/\/dpress.ma\/fr\/2026\/05\/12\/previsions-meteorologiques-pour-mardi-12-mai-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dpress.ma\/fr\/"},{"@type":"ListItem","position":2,"name":"Pr\u00e9visions m\u00e9t\u00e9orologiques pour mardi 12 mai 2026"}]},{"@type":"WebSite","@id":"https:\/\/dpress.ma\/fr\/#website","url":"https:\/\/dpress.ma\/fr\/","name":"Dpress.ma\/fr","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dpress.ma\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/dpress.ma\/fr\/#\/schema\/person\/4898febf3ccd59e6578d838656a306a0","name":"Dpress.ma","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/72ecc30e9db047a2e0e7176561eb9d564ed77c8108376495b19bd8336405198a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/72ecc30e9db047a2e0e7176561eb9d564ed77c8108376495b19bd8336405198a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/72ecc30e9db047a2e0e7176561eb9d564ed77c8108376495b19bd8336405198a?s=96&d=mm&r=g","caption":"Dpress.ma"},"sameAs":["https:\/\/www.dpress.ma"],"url":"https:\/\/dpress.ma\/fr\/author\/dpress-ma\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/posts\/30747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/comments?post=30747"}],"version-history":[{"count":1,"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/posts\/30747\/revisions"}],"predecessor-version":[{"id":30748,"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/posts\/30747\/revisions\/30748"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/media\/30629"}],"wp:attachment":[{"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/media?parent=30747"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/categories?post=30747"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/tags?post=30747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}