{"id":30744,"date":"2026-05-12T10:29:08","date_gmt":"2026-05-12T10:29:08","guid":{"rendered":"https:\/\/dpress.ma\/fr\/?p=30744"},"modified":"2026-05-12T10:29:17","modified_gmt":"2026-05-12T10:29:17","slug":"des-materiaux-vivants-a-lia-les-fes-design-days-2026-reinventent-larchitecture-durable","status":"publish","type":"post","link":"https:\/\/dpress.ma\/fr\/2026\/05\/12\/des-materiaux-vivants-a-lia-les-fes-design-days-2026-reinventent-larchitecture-durable\/","title":{"rendered":"Des mat\u00e9riaux vivants \u00e0 l\u2019IA: les \u201cF\u00e8s Design Days 2026\u201d r\u00e9inventent l\u2019architecture durable"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Dpress<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les \u201cF\u00e8s Design Days 2026\u201d d\u00e9di\u00e9s \u00e0 l\u2019exploration de nouvelles approches de l\u2019architecture durable \u00e0 travers une r\u00e9flexion crois\u00e9e de sp\u00e9cialistes et chercheurs marocains et \u00e9trangers, se sont ouverts, lundi \u00e0 F\u00e8s, \u00e0 l\u2019initiative de&nbsp;l\u2019Universit\u00e9 Priv\u00e9e de F\u00e8s (UPF).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Des mat\u00e9riaux biosourc\u00e9s issus de biod\u00e9chets organiques aux technologies d\u2019intelligence artificielle appliqu\u00e9es \u00e0 la conception architecturale, les participants dont des architectes, designers, chercheurs, artistes et professionnels devront se pencher jusqu\u2019au 15 mai courant, sur l\u2019analyse des mutations \u00e9cologiques et technologiques qui red\u00e9finissent les m\u00e9tiers de la cr\u00e9ation.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">S\u2019exprimant \u00e0 l\u2019ouverture de ces journ\u00e9es, le pr\u00e9sident de l\u2019Universit\u00e9 Priv\u00e9e de F\u00e8s (UPF), Mohamed Aziz Lahlou, a soulign\u00e9 que cette manifestation traduit l\u2019ambition de l\u2019universit\u00e9 de former des profils capables d\u2019imaginer et de transformer le monde de demain, dans un contexte marqu\u00e9 par de profondes mutations technologiques, environnementales, sociales et culturelles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A cet \u00e9gard, il a relev\u00e9 que \u201cl\u2019innovation na\u00eet de la rencontre entre les disciplines\u201d, mettant en avant le choix de l\u2019UPF de faire de \u201cl\u2019interdisciplinarit\u00e9, de la cr\u00e9ativit\u00e9 et de l\u2019ouverture sur le monde les piliers de son projet acad\u00e9mique\u201d, \u00e0 travers un espace d\u2019\u00e9change r\u00e9unissant architectes, designers, artistes, ing\u00e9nieurs, chercheurs, entreprises et jeunes talents autour des enjeux contemporains li\u00e9s aux espaces, aux usages et \u00e0 la qualit\u00e9 de vie.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il a \u00e9galement soulign\u00e9 que le design et l\u2019architecture sont devenus de v\u00e9ritables leviers de transformation sociale, \u00e9conomique et environnementale, d\u00e9passant d\u00e9sormais leur seule dimension esth\u00e9tique pour int\u00e9grer les probl\u00e9matiques de durabilit\u00e9, d\u2019efficacit\u00e9 \u00e9nerg\u00e9tique, d\u2019intelligence technologique et d\u2019inclusion.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De son c\u00f4t\u00e9, l\u2019architecte et enseignante \u00e0 l\u2019Universit\u00e9 europ\u00e9enne de Madrid, Angela Ruiz a mis en avant, lors de la conf\u00e9rence inaugurale, les avanc\u00e9es de l\u2019architecture biosourc\u00e9e, une approche qui s\u2019inspire de l\u2019\u00e9cologie et des m\u00e9canismes du vivant afin de concevoir des espaces plus durables et respectueux de l\u2019environnement, expliquant que cette d\u00e9marche d\u00e9passe l\u2019utilisation traditionnelle de mat\u00e9riaux naturels comme la terre ou la paille, en int\u00e9grant \u00e9galement de nouveaux mat\u00e9riaux issus de biod\u00e9chets organiques, notamment les coquilles marines, les coquilles d\u2019\u0153ufs ou encore les r\u00e9sidus v\u00e9g\u00e9taux tels que les pelures d\u2019orange.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mme Ruiz a \u00e9galement soulign\u00e9 que le biomim\u00e9tisme occupe d\u00e9sormais une place croissante dans la recherche architecturale contemporaine, pr\u00e9cisant que plusieurs exp\u00e9riences s\u2019inspirent directement des m\u00e9canismes naturels pour d\u00e9velopper des mat\u00e9riaux innovants et biod\u00e9gradables.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Elle a cit\u00e9, dans ce sens, l\u2019utilisation de bact\u00e9ries, d\u2019algues ou de micro-organismes capables de renforcer ou de durcir certains composants de construction de mani\u00e8re naturelle, ouvrant la voie \u00e0 des alternatives moins polluantes et \u00e0 faible impact environnemental, ajoutant que l\u2019apport grandissant de l\u2019intelligence artificielle dans ce domaine, permet en outre, d\u2019acc\u00e9l\u00e9rer la recherche sur de nouveaux mat\u00e9riaux \u00e9cologiques, d\u2019analyser leurs performances et d\u2019imaginer des solutions architecturales inspir\u00e9es des formes et des \u00e9quilibres observ\u00e9s dans la nature.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans une d\u00e9claration \u00e0 la MAP, le directeur de l\u2019Ecole Sup\u00e9rieure des M\u00e9tiers de l\u2019Architecture et du B\u00e2timent au sein de l\u2019UPF, Mustapha Akalay a indiqu\u00e9 que tout au long de la semaine, cet \u00e9v\u00e8nement r\u00e9unira un large panel de sp\u00e9cialistes, notamment des architectes, designers, urbanistes et praticiens appel\u00e9s \u00e0 d\u00e9battre des enjeux contemporains li\u00e9s \u00e0 la conception des espaces et des usages, ajoutant que cette \u00e9dition sera marqu\u00e9e par plusieurs expositions artistiques et architecturales qui mettront en avant les travaux d\u2019enseignants et de cr\u00e9ateurs invit\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De son c\u00f4t\u00e9, l\u2019architecte barcelonais Octavio Mestre a indiqu\u00e9 que \u201cF\u00e8s Design Days\u201d sera l\u2019occasion de pr\u00e9senter son exp\u00e9rience professionnelle et de renforcer les \u00e9changes avec les architectes marocains, soulignant les liens d\u00e9velopp\u00e9s avec plusieurs acteurs du secteur au Maroc au fil de ses visites au Royaume.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mestre a \u00e9galement mis en avant son initiative \u00e9ditoriale \u00e0 travers la revue num\u00e9rique sp\u00e9cialis\u00e9e \u201cT18\u201d, diffus\u00e9e \u00e0 l\u2019international, pr\u00e9cisant qu\u2019un num\u00e9ro sp\u00e9cial de plus de 400 pages a \u00e9t\u00e9 consacr\u00e9 \u00e0 l\u2019architecture marocaine contemporaine, avec un int\u00e9r\u00eat particulier aux jeunes et aux femmes architectes marocains.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Organis\u00e9e sous le th\u00e8me \u201cArchitectures et Design durables dans un monde en transitions\u201d, cette \u00e9dition des \u201cF\u00e8s Design Days 2026\u201d pr\u00e9voit&nbsp; des conf\u00e9rences consacr\u00e9es aux nouvelles approches du design et de l\u2019architecture, ainsi que des \u00e9changes autour de la valorisation du patrimoine, de l\u2019innovation urbaine et des d\u00e9fis environnementaux qui red\u00e9finissent aujourd\u2019hui les pratiques architecturales et artistiques.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dpress Les \u201cF\u00e8s Design Days 2026\u201d d\u00e9di\u00e9s \u00e0 l\u2019exploration de nouvelles approches de l\u2019architecture durable \u00e0 travers une r\u00e9flexion crois\u00e9e de sp\u00e9cialistes et chercheurs marocains et \u00e9trangers, se sont ouverts, lundi \u00e0 F\u00e8s, \u00e0 l\u2019initiative de&nbsp;l\u2019Universit\u00e9 Priv\u00e9e de F\u00e8s (UPF). Des mat\u00e9riaux biosourc\u00e9s issus de biod\u00e9chets organiques aux technologies d\u2019intelligence artificielle appliqu\u00e9es \u00e0 la conception &hellip;<\/p>\n","protected":false},"author":2,"featured_media":30745,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[40],"tags":[],"class_list":["post-30744","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-societe-et-regions"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Des mat\u00e9riaux vivants \u00e0 l\u2019IA: les \u201cF\u00e8s Design Days 2026\u201d r\u00e9inventent l\u2019architecture durable - Dpress.ma\/fr<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dpress.ma\/fr\/2026\/05\/12\/des-materiaux-vivants-a-lia-les-fes-design-days-2026-reinventent-larchitecture-durable\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Des mat\u00e9riaux vivants \u00e0 l\u2019IA: les \u201cF\u00e8s Design Days 2026\u201d r\u00e9inventent l\u2019architecture durable - Dpress.ma\/fr\" \/>\n<meta property=\"og:description\" content=\"Dpress Les \u201cF\u00e8s Design Days 2026\u201d d\u00e9di\u00e9s \u00e0 l\u2019exploration de nouvelles approches de l\u2019architecture durable \u00e0 travers une r\u00e9flexion crois\u00e9e de sp\u00e9cialistes et chercheurs marocains et \u00e9trangers, se sont ouverts, lundi \u00e0 F\u00e8s, \u00e0 l\u2019initiative de&nbsp;l\u2019Universit\u00e9 Priv\u00e9e de F\u00e8s (UPF). Des mat\u00e9riaux biosourc\u00e9s issus de biod\u00e9chets organiques aux technologies d\u2019intelligence artificielle appliqu\u00e9es \u00e0 la conception &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dpress.ma\/fr\/2026\/05\/12\/des-materiaux-vivants-a-lia-les-fes-design-days-2026-reinventent-larchitecture-durable\/\" \/>\n<meta property=\"og:site_name\" content=\"Dpress.ma\/fr\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-12T10:29:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T10:29:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dpress.ma\/fr\/wp-content\/uploads\/sites\/2\/2026\/05\/57-5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2539\" \/>\n\t<meta property=\"og:image:height\" content=\"1594\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dpress.ma\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dpress.ma\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/12\\\/des-materiaux-vivants-a-lia-les-fes-design-days-2026-reinventent-larchitecture-durable\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/12\\\/des-materiaux-vivants-a-lia-les-fes-design-days-2026-reinventent-larchitecture-durable\\\/\"},\"author\":{\"name\":\"Dpress.ma\",\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/#\\\/schema\\\/person\\\/4898febf3ccd59e6578d838656a306a0\"},\"headline\":\"Des mat\u00e9riaux vivants \u00e0 l\u2019IA: les \u201cF\u00e8s Design Days 2026\u201d r\u00e9inventent l\u2019architecture durable\",\"datePublished\":\"2026-05-12T10:29:08+00:00\",\"dateModified\":\"2026-05-12T10:29:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/12\\\/des-materiaux-vivants-a-lia-les-fes-design-days-2026-reinventent-larchitecture-durable\\\/\"},\"wordCount\":836,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/12\\\/des-materiaux-vivants-a-lia-les-fes-design-days-2026-reinventent-larchitecture-durable\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/05\\\/57-5.jpg\",\"articleSection\":[\"societe et regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/12\\\/des-materiaux-vivants-a-lia-les-fes-design-days-2026-reinventent-larchitecture-durable\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/12\\\/des-materiaux-vivants-a-lia-les-fes-design-days-2026-reinventent-larchitecture-durable\\\/\",\"url\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/12\\\/des-materiaux-vivants-a-lia-les-fes-design-days-2026-reinventent-larchitecture-durable\\\/\",\"name\":\"Des mat\u00e9riaux vivants \u00e0 l\u2019IA: les \u201cF\u00e8s Design Days 2026\u201d r\u00e9inventent l\u2019architecture durable - Dpress.ma\\\/fr\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/12\\\/des-materiaux-vivants-a-lia-les-fes-design-days-2026-reinventent-larchitecture-durable\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/12\\\/des-materiaux-vivants-a-lia-les-fes-design-days-2026-reinventent-larchitecture-durable\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/05\\\/57-5.jpg\",\"datePublished\":\"2026-05-12T10:29:08+00:00\",\"dateModified\":\"2026-05-12T10:29:17+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/#\\\/schema\\\/person\\\/4898febf3ccd59e6578d838656a306a0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/12\\\/des-materiaux-vivants-a-lia-les-fes-design-days-2026-reinventent-larchitecture-durable\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/12\\\/des-materiaux-vivants-a-lia-les-fes-design-days-2026-reinventent-larchitecture-durable\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/12\\\/des-materiaux-vivants-a-lia-les-fes-design-days-2026-reinventent-larchitecture-durable\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/05\\\/57-5.jpg\",\"contentUrl\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/05\\\/57-5.jpg\",\"width\":2539,\"height\":1594},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/12\\\/des-materiaux-vivants-a-lia-les-fes-design-days-2026-reinventent-larchitecture-durable\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Des mat\u00e9riaux vivants \u00e0 l\u2019IA: les \u201cF\u00e8s Design Days 2026\u201d r\u00e9inventent l\u2019architecture durable\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/\",\"name\":\"Dpress.ma\\\/fr\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/#\\\/schema\\\/person\\\/4898febf3ccd59e6578d838656a306a0\",\"name\":\"Dpress.ma\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72ecc30e9db047a2e0e7176561eb9d564ed77c8108376495b19bd8336405198a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72ecc30e9db047a2e0e7176561eb9d564ed77c8108376495b19bd8336405198a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72ecc30e9db047a2e0e7176561eb9d564ed77c8108376495b19bd8336405198a?s=96&d=mm&r=g\",\"caption\":\"Dpress.ma\"},\"sameAs\":[\"https:\\\/\\\/www.dpress.ma\"],\"url\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/author\\\/dpress-ma\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Des mat\u00e9riaux vivants \u00e0 l\u2019IA: les \u201cF\u00e8s Design Days 2026\u201d r\u00e9inventent l\u2019architecture durable - Dpress.ma\/fr","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dpress.ma\/fr\/2026\/05\/12\/des-materiaux-vivants-a-lia-les-fes-design-days-2026-reinventent-larchitecture-durable\/","og_locale":"fr_FR","og_type":"article","og_title":"Des mat\u00e9riaux vivants \u00e0 l\u2019IA: les \u201cF\u00e8s Design Days 2026\u201d r\u00e9inventent l\u2019architecture durable - Dpress.ma\/fr","og_description":"Dpress Les \u201cF\u00e8s Design Days 2026\u201d d\u00e9di\u00e9s \u00e0 l\u2019exploration de nouvelles approches de l\u2019architecture durable \u00e0 travers une r\u00e9flexion crois\u00e9e de sp\u00e9cialistes et chercheurs marocains et \u00e9trangers, se sont ouverts, lundi \u00e0 F\u00e8s, \u00e0 l\u2019initiative de&nbsp;l\u2019Universit\u00e9 Priv\u00e9e de F\u00e8s (UPF). Des mat\u00e9riaux biosourc\u00e9s issus de biod\u00e9chets organiques aux technologies d\u2019intelligence artificielle appliqu\u00e9es \u00e0 la conception &hellip;","og_url":"https:\/\/dpress.ma\/fr\/2026\/05\/12\/des-materiaux-vivants-a-lia-les-fes-design-days-2026-reinventent-larchitecture-durable\/","og_site_name":"Dpress.ma\/fr","article_published_time":"2026-05-12T10:29:08+00:00","article_modified_time":"2026-05-12T10:29:17+00:00","og_image":[{"width":2539,"height":1594,"url":"https:\/\/dpress.ma\/fr\/wp-content\/uploads\/sites\/2\/2026\/05\/57-5.jpg","type":"image\/jpeg"}],"author":"Dpress.ma","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Dpress.ma","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dpress.ma\/fr\/2026\/05\/12\/des-materiaux-vivants-a-lia-les-fes-design-days-2026-reinventent-larchitecture-durable\/#article","isPartOf":{"@id":"https:\/\/dpress.ma\/fr\/2026\/05\/12\/des-materiaux-vivants-a-lia-les-fes-design-days-2026-reinventent-larchitecture-durable\/"},"author":{"name":"Dpress.ma","@id":"https:\/\/dpress.ma\/fr\/#\/schema\/person\/4898febf3ccd59e6578d838656a306a0"},"headline":"Des mat\u00e9riaux vivants \u00e0 l\u2019IA: les \u201cF\u00e8s Design Days 2026\u201d r\u00e9inventent l\u2019architecture durable","datePublished":"2026-05-12T10:29:08+00:00","dateModified":"2026-05-12T10:29:17+00:00","mainEntityOfPage":{"@id":"https:\/\/dpress.ma\/fr\/2026\/05\/12\/des-materiaux-vivants-a-lia-les-fes-design-days-2026-reinventent-larchitecture-durable\/"},"wordCount":836,"commentCount":0,"image":{"@id":"https:\/\/dpress.ma\/fr\/2026\/05\/12\/des-materiaux-vivants-a-lia-les-fes-design-days-2026-reinventent-larchitecture-durable\/#primaryimage"},"thumbnailUrl":"https:\/\/dpress.ma\/fr\/wp-content\/uploads\/sites\/2\/2026\/05\/57-5.jpg","articleSection":["societe et regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dpress.ma\/fr\/2026\/05\/12\/des-materiaux-vivants-a-lia-les-fes-design-days-2026-reinventent-larchitecture-durable\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dpress.ma\/fr\/2026\/05\/12\/des-materiaux-vivants-a-lia-les-fes-design-days-2026-reinventent-larchitecture-durable\/","url":"https:\/\/dpress.ma\/fr\/2026\/05\/12\/des-materiaux-vivants-a-lia-les-fes-design-days-2026-reinventent-larchitecture-durable\/","name":"Des mat\u00e9riaux vivants \u00e0 l\u2019IA: les \u201cF\u00e8s Design Days 2026\u201d r\u00e9inventent l\u2019architecture durable - Dpress.ma\/fr","isPartOf":{"@id":"https:\/\/dpress.ma\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dpress.ma\/fr\/2026\/05\/12\/des-materiaux-vivants-a-lia-les-fes-design-days-2026-reinventent-larchitecture-durable\/#primaryimage"},"image":{"@id":"https:\/\/dpress.ma\/fr\/2026\/05\/12\/des-materiaux-vivants-a-lia-les-fes-design-days-2026-reinventent-larchitecture-durable\/#primaryimage"},"thumbnailUrl":"https:\/\/dpress.ma\/fr\/wp-content\/uploads\/sites\/2\/2026\/05\/57-5.jpg","datePublished":"2026-05-12T10:29:08+00:00","dateModified":"2026-05-12T10:29:17+00:00","author":{"@id":"https:\/\/dpress.ma\/fr\/#\/schema\/person\/4898febf3ccd59e6578d838656a306a0"},"breadcrumb":{"@id":"https:\/\/dpress.ma\/fr\/2026\/05\/12\/des-materiaux-vivants-a-lia-les-fes-design-days-2026-reinventent-larchitecture-durable\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dpress.ma\/fr\/2026\/05\/12\/des-materiaux-vivants-a-lia-les-fes-design-days-2026-reinventent-larchitecture-durable\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dpress.ma\/fr\/2026\/05\/12\/des-materiaux-vivants-a-lia-les-fes-design-days-2026-reinventent-larchitecture-durable\/#primaryimage","url":"https:\/\/dpress.ma\/fr\/wp-content\/uploads\/sites\/2\/2026\/05\/57-5.jpg","contentUrl":"https:\/\/dpress.ma\/fr\/wp-content\/uploads\/sites\/2\/2026\/05\/57-5.jpg","width":2539,"height":1594},{"@type":"BreadcrumbList","@id":"https:\/\/dpress.ma\/fr\/2026\/05\/12\/des-materiaux-vivants-a-lia-les-fes-design-days-2026-reinventent-larchitecture-durable\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dpress.ma\/fr\/"},{"@type":"ListItem","position":2,"name":"Des mat\u00e9riaux vivants \u00e0 l\u2019IA: les \u201cF\u00e8s Design Days 2026\u201d r\u00e9inventent l\u2019architecture durable"}]},{"@type":"WebSite","@id":"https:\/\/dpress.ma\/fr\/#website","url":"https:\/\/dpress.ma\/fr\/","name":"Dpress.ma\/fr","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dpress.ma\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/dpress.ma\/fr\/#\/schema\/person\/4898febf3ccd59e6578d838656a306a0","name":"Dpress.ma","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/72ecc30e9db047a2e0e7176561eb9d564ed77c8108376495b19bd8336405198a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/72ecc30e9db047a2e0e7176561eb9d564ed77c8108376495b19bd8336405198a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/72ecc30e9db047a2e0e7176561eb9d564ed77c8108376495b19bd8336405198a?s=96&d=mm&r=g","caption":"Dpress.ma"},"sameAs":["https:\/\/www.dpress.ma"],"url":"https:\/\/dpress.ma\/fr\/author\/dpress-ma\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/posts\/30744","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/comments?post=30744"}],"version-history":[{"count":1,"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/posts\/30744\/revisions"}],"predecessor-version":[{"id":30746,"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/posts\/30744\/revisions\/30746"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/media\/30745"}],"wp:attachment":[{"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/media?parent=30744"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/categories?post=30744"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/tags?post=30744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}