{"id":30708,"date":"2026-05-12T10:08:12","date_gmt":"2026-05-12T10:08:12","guid":{"rendered":"https:\/\/dpress.ma\/fr\/?p=30708"},"modified":"2026-05-12T10:08:14","modified_gmt":"2026-05-12T10:08:14","slug":"les-activites-parascolaires-et-les-cellules-de-veille-contribuent-a-lutter-contre-la-deperdition-scolaire","status":"publish","type":"post","link":"https:\/\/dpress.ma\/fr\/2026\/05\/12\/les-activites-parascolaires-et-les-cellules-de-veille-contribuent-a-lutter-contre-la-deperdition-scolaire\/","title":{"rendered":"Les activit\u00e9s parascolaires et les cellules de veille contribuent \u00e0 lutter contre la d\u00e9perdition scolaire"},"content":{"rendered":"\n<p>Dpress<\/p>\n\n\n\n<p>Les activit\u00e9s parascolaires et les cellules de veillent contribuent \u00e0 lutter contre la d\u00e9perdition scolaire au sein des coll\u00e8ges pionniers, a affirm\u00e9&nbsp;lundi \u00e0 la Chambre des repr\u00e9sentants, le&nbsp;ministre de l\u2019\u00c9ducation nationale, du Pr\u00e9scolaire et des Sports,&nbsp;Mohamed Saad Berrada.<\/p>\n\n\n\n<p>Les activit\u00e9s parascolaires ont permis de&nbsp;\u201ctr\u00e8s bons\u201d&nbsp;r\u00e9sultats en mati\u00e8re de lutte contre le d\u00e9crochage scolaire, a indiqu\u00e9 le ministre, en r\u00e9ponse \u00e0 une question orale sur \u201cl\u2019exp\u00e9rience des \u00e9tablissements pionniers\u201d.<\/p>\n\n\n\n<p>Il a estim\u00e9 que la participation des \u00e9l\u00e8ves \u00e0 des activit\u00e9s comme le th\u00e9\u00e2tre, le sport, le cin\u00e9ma ou la robotique \u00e0 raison de deux heures hebdomadaires, \u00e9rige l\u2019\u00e9cole en un espace de loisirs et d\u2019apprentissage, notant que les cellules de veille ont accompagn\u00e9 les \u00e9l\u00e8ves menac\u00e9s de d\u00e9crochage.<\/p>\n\n\n\n<p>Environ 20% des \u00e9l\u00e8ves ayant abandonn\u00e9 l\u2019\u00e9cole ou qui sont expos\u00e9s \u00e0 ce risque b\u00e9n\u00e9ficient de l\u2019accompagnement de ces cellules, qui prennent contact avec leurs tuteurs afin d\u2019en d\u00e9terminer les causes des absences et d\u2019y rem\u00e9dier, a expliqu\u00e9 le ministre.<\/p>\n\n\n\n<p>Il s\u2019agit aussi, a-t-il dit, d\u2019accompagner les \u00e9l\u00e8ves souffrant de probl\u00e8mes psychiques et familiaux ou de difficult\u00e9s d\u2019apprentissage, tout en leur accordant la priorit\u00e9 pour les cours de soutien.<\/p>\n\n\n\n<p>Par ailleurs, M. Berrada a relev\u00e9 que le nombre des \u00e9coles primaires pionni\u00e8res atteindra 6.626 lors de la prochaine rentr\u00e9e sur 8.500 (80% du total des \u00e9tablissements), tandis que les coll\u00e8ges pionniers compteront 1.230 \u00e9tablissements en septembre prochain (50%).<\/p>\n\n\n\n<p>Il a aussi \u00e9voqu\u00e9 plusieurs outils adopt\u00e9s au sein des \u00e9coles pionni\u00e8res comme les cours intensifs au profit des \u00e9l\u00e8ves dans les mati\u00e8res fondamentales, l\u2019adoption de la m\u00e9thode \u201cTaRL\u201d (enseigner au bon niveau) et de l&rsquo;\u201dExplicite\u201d, outre des \u00e9valuations p\u00e9riodiques chaque six semaines, o\u00f9 plus de 3 millions d\u2019\u00e9l\u00e8ves passent des examens normalis\u00e9s \u00e0 l\u2019\u00e9chelle nationale.<\/p>\n\n\n\n<p>Cette d\u00e9marche permet de comparer les r\u00e9sultats des \u00e9l\u00e8ves, des classes et des \u00e9tablissements, de d\u00e9tecter les difficult\u00e9s et d\u2019apporter le soutien continu aux \u00e9l\u00e8ves et aux \u00e9tablissements en difficult\u00e9, a-t-il poursuivi.<\/p>\n\n\n\n<p>Outre le syst\u00e8me d\u2019\u00e9valuation, le minist\u00e8re a adopt\u00e9 un m\u00e9canisme d\u2019homologation des corrections dans l\u2019objectif d\u2019unifier les standards et de garantir la comparabilit\u00e9 et l\u2019am\u00e9lioration des r\u00e9sultats, a relev\u00e9 M. Berrada, notant que les inspecteurs se chargent de l\u2019homologation interne, aux c\u00f4t\u00e9s d\u2019une homologation externe en vue de v\u00e9rifier l\u2019exactitude des \u00e9valuations.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dpress Les activit\u00e9s parascolaires et les cellules de veillent contribuent \u00e0 lutter contre la d\u00e9perdition scolaire au sein des coll\u00e8ges pionniers, a affirm\u00e9&nbsp;lundi \u00e0 la Chambre des repr\u00e9sentants, le&nbsp;ministre de l\u2019\u00c9ducation nationale, du Pr\u00e9scolaire et des Sports,&nbsp;Mohamed Saad Berrada. Les activit\u00e9s parascolaires ont permis de&nbsp;\u201ctr\u00e8s bons\u201d&nbsp;r\u00e9sultats en mati\u00e8re de lutte contre le d\u00e9crochage scolaire, a &hellip;<\/p>\n","protected":false},"author":2,"featured_media":30709,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[],"class_list":["post-30708","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politiques"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les activit\u00e9s parascolaires et les cellules de veille contribuent \u00e0 lutter contre la d\u00e9perdition scolaire - Dpress.ma\/fr<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dpress.ma\/fr\/2026\/05\/12\/les-activites-parascolaires-et-les-cellules-de-veille-contribuent-a-lutter-contre-la-deperdition-scolaire\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les activit\u00e9s parascolaires et les cellules de veille contribuent \u00e0 lutter contre la d\u00e9perdition scolaire - Dpress.ma\/fr\" \/>\n<meta property=\"og:description\" content=\"Dpress Les activit\u00e9s parascolaires et les cellules de veillent contribuent \u00e0 lutter contre la d\u00e9perdition scolaire au sein des coll\u00e8ges pionniers, a affirm\u00e9&nbsp;lundi \u00e0 la Chambre des repr\u00e9sentants, le&nbsp;ministre de l\u2019\u00c9ducation nationale, du Pr\u00e9scolaire et des Sports,&nbsp;Mohamed Saad Berrada. Les activit\u00e9s parascolaires ont permis de&nbsp;\u201ctr\u00e8s bons\u201d&nbsp;r\u00e9sultats en mati\u00e8re de lutte contre le d\u00e9crochage scolaire, a &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dpress.ma\/fr\/2026\/05\/12\/les-activites-parascolaires-et-les-cellules-de-veille-contribuent-a-lutter-contre-la-deperdition-scolaire\/\" \/>\n<meta property=\"og:site_name\" content=\"Dpress.ma\/fr\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-12T10:08:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T10:08:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dpress.ma\/fr\/wp-content\/uploads\/sites\/2\/2026\/05\/46-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2539\" \/>\n\t<meta property=\"og:image:height\" content=\"1594\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dpress.ma\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dpress.ma\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/12\\\/les-activites-parascolaires-et-les-cellules-de-veille-contribuent-a-lutter-contre-la-deperdition-scolaire\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/12\\\/les-activites-parascolaires-et-les-cellules-de-veille-contribuent-a-lutter-contre-la-deperdition-scolaire\\\/\"},\"author\":{\"name\":\"Dpress.ma\",\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/#\\\/schema\\\/person\\\/4898febf3ccd59e6578d838656a306a0\"},\"headline\":\"Les activit\u00e9s parascolaires et les cellules de veille contribuent \u00e0 lutter contre la d\u00e9perdition scolaire\",\"datePublished\":\"2026-05-12T10:08:12+00:00\",\"dateModified\":\"2026-05-12T10:08:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/12\\\/les-activites-parascolaires-et-les-cellules-de-veille-contribuent-a-lutter-contre-la-deperdition-scolaire\\\/\"},\"wordCount\":455,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/12\\\/les-activites-parascolaires-et-les-cellules-de-veille-contribuent-a-lutter-contre-la-deperdition-scolaire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/05\\\/46-4.jpg\",\"articleSection\":[\"Politiques\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/12\\\/les-activites-parascolaires-et-les-cellules-de-veille-contribuent-a-lutter-contre-la-deperdition-scolaire\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/12\\\/les-activites-parascolaires-et-les-cellules-de-veille-contribuent-a-lutter-contre-la-deperdition-scolaire\\\/\",\"url\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/12\\\/les-activites-parascolaires-et-les-cellules-de-veille-contribuent-a-lutter-contre-la-deperdition-scolaire\\\/\",\"name\":\"Les activit\u00e9s parascolaires et les cellules de veille contribuent \u00e0 lutter contre la d\u00e9perdition scolaire - Dpress.ma\\\/fr\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/12\\\/les-activites-parascolaires-et-les-cellules-de-veille-contribuent-a-lutter-contre-la-deperdition-scolaire\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/12\\\/les-activites-parascolaires-et-les-cellules-de-veille-contribuent-a-lutter-contre-la-deperdition-scolaire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/05\\\/46-4.jpg\",\"datePublished\":\"2026-05-12T10:08:12+00:00\",\"dateModified\":\"2026-05-12T10:08:14+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/#\\\/schema\\\/person\\\/4898febf3ccd59e6578d838656a306a0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/12\\\/les-activites-parascolaires-et-les-cellules-de-veille-contribuent-a-lutter-contre-la-deperdition-scolaire\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/12\\\/les-activites-parascolaires-et-les-cellules-de-veille-contribuent-a-lutter-contre-la-deperdition-scolaire\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/12\\\/les-activites-parascolaires-et-les-cellules-de-veille-contribuent-a-lutter-contre-la-deperdition-scolaire\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/05\\\/46-4.jpg\",\"contentUrl\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/05\\\/46-4.jpg\",\"width\":2539,\"height\":1594},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/12\\\/les-activites-parascolaires-et-les-cellules-de-veille-contribuent-a-lutter-contre-la-deperdition-scolaire\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les activit\u00e9s parascolaires et les cellules de veille contribuent \u00e0 lutter contre la d\u00e9perdition scolaire\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/\",\"name\":\"Dpress.ma\\\/fr\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/#\\\/schema\\\/person\\\/4898febf3ccd59e6578d838656a306a0\",\"name\":\"Dpress.ma\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72ecc30e9db047a2e0e7176561eb9d564ed77c8108376495b19bd8336405198a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72ecc30e9db047a2e0e7176561eb9d564ed77c8108376495b19bd8336405198a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72ecc30e9db047a2e0e7176561eb9d564ed77c8108376495b19bd8336405198a?s=96&d=mm&r=g\",\"caption\":\"Dpress.ma\"},\"sameAs\":[\"https:\\\/\\\/www.dpress.ma\"],\"url\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/author\\\/dpress-ma\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les activit\u00e9s parascolaires et les cellules de veille contribuent \u00e0 lutter contre la d\u00e9perdition scolaire - Dpress.ma\/fr","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dpress.ma\/fr\/2026\/05\/12\/les-activites-parascolaires-et-les-cellules-de-veille-contribuent-a-lutter-contre-la-deperdition-scolaire\/","og_locale":"fr_FR","og_type":"article","og_title":"Les activit\u00e9s parascolaires et les cellules de veille contribuent \u00e0 lutter contre la d\u00e9perdition scolaire - Dpress.ma\/fr","og_description":"Dpress Les activit\u00e9s parascolaires et les cellules de veillent contribuent \u00e0 lutter contre la d\u00e9perdition scolaire au sein des coll\u00e8ges pionniers, a affirm\u00e9&nbsp;lundi \u00e0 la Chambre des repr\u00e9sentants, le&nbsp;ministre de l\u2019\u00c9ducation nationale, du Pr\u00e9scolaire et des Sports,&nbsp;Mohamed Saad Berrada. Les activit\u00e9s parascolaires ont permis de&nbsp;\u201ctr\u00e8s bons\u201d&nbsp;r\u00e9sultats en mati\u00e8re de lutte contre le d\u00e9crochage scolaire, a &hellip;","og_url":"https:\/\/dpress.ma\/fr\/2026\/05\/12\/les-activites-parascolaires-et-les-cellules-de-veille-contribuent-a-lutter-contre-la-deperdition-scolaire\/","og_site_name":"Dpress.ma\/fr","article_published_time":"2026-05-12T10:08:12+00:00","article_modified_time":"2026-05-12T10:08:14+00:00","og_image":[{"width":2539,"height":1594,"url":"https:\/\/dpress.ma\/fr\/wp-content\/uploads\/sites\/2\/2026\/05\/46-4.jpg","type":"image\/jpeg"}],"author":"Dpress.ma","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Dpress.ma","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dpress.ma\/fr\/2026\/05\/12\/les-activites-parascolaires-et-les-cellules-de-veille-contribuent-a-lutter-contre-la-deperdition-scolaire\/#article","isPartOf":{"@id":"https:\/\/dpress.ma\/fr\/2026\/05\/12\/les-activites-parascolaires-et-les-cellules-de-veille-contribuent-a-lutter-contre-la-deperdition-scolaire\/"},"author":{"name":"Dpress.ma","@id":"https:\/\/dpress.ma\/fr\/#\/schema\/person\/4898febf3ccd59e6578d838656a306a0"},"headline":"Les activit\u00e9s parascolaires et les cellules de veille contribuent \u00e0 lutter contre la d\u00e9perdition scolaire","datePublished":"2026-05-12T10:08:12+00:00","dateModified":"2026-05-12T10:08:14+00:00","mainEntityOfPage":{"@id":"https:\/\/dpress.ma\/fr\/2026\/05\/12\/les-activites-parascolaires-et-les-cellules-de-veille-contribuent-a-lutter-contre-la-deperdition-scolaire\/"},"wordCount":455,"commentCount":0,"image":{"@id":"https:\/\/dpress.ma\/fr\/2026\/05\/12\/les-activites-parascolaires-et-les-cellules-de-veille-contribuent-a-lutter-contre-la-deperdition-scolaire\/#primaryimage"},"thumbnailUrl":"https:\/\/dpress.ma\/fr\/wp-content\/uploads\/sites\/2\/2026\/05\/46-4.jpg","articleSection":["Politiques"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dpress.ma\/fr\/2026\/05\/12\/les-activites-parascolaires-et-les-cellules-de-veille-contribuent-a-lutter-contre-la-deperdition-scolaire\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dpress.ma\/fr\/2026\/05\/12\/les-activites-parascolaires-et-les-cellules-de-veille-contribuent-a-lutter-contre-la-deperdition-scolaire\/","url":"https:\/\/dpress.ma\/fr\/2026\/05\/12\/les-activites-parascolaires-et-les-cellules-de-veille-contribuent-a-lutter-contre-la-deperdition-scolaire\/","name":"Les activit\u00e9s parascolaires et les cellules de veille contribuent \u00e0 lutter contre la d\u00e9perdition scolaire - Dpress.ma\/fr","isPartOf":{"@id":"https:\/\/dpress.ma\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dpress.ma\/fr\/2026\/05\/12\/les-activites-parascolaires-et-les-cellules-de-veille-contribuent-a-lutter-contre-la-deperdition-scolaire\/#primaryimage"},"image":{"@id":"https:\/\/dpress.ma\/fr\/2026\/05\/12\/les-activites-parascolaires-et-les-cellules-de-veille-contribuent-a-lutter-contre-la-deperdition-scolaire\/#primaryimage"},"thumbnailUrl":"https:\/\/dpress.ma\/fr\/wp-content\/uploads\/sites\/2\/2026\/05\/46-4.jpg","datePublished":"2026-05-12T10:08:12+00:00","dateModified":"2026-05-12T10:08:14+00:00","author":{"@id":"https:\/\/dpress.ma\/fr\/#\/schema\/person\/4898febf3ccd59e6578d838656a306a0"},"breadcrumb":{"@id":"https:\/\/dpress.ma\/fr\/2026\/05\/12\/les-activites-parascolaires-et-les-cellules-de-veille-contribuent-a-lutter-contre-la-deperdition-scolaire\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dpress.ma\/fr\/2026\/05\/12\/les-activites-parascolaires-et-les-cellules-de-veille-contribuent-a-lutter-contre-la-deperdition-scolaire\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dpress.ma\/fr\/2026\/05\/12\/les-activites-parascolaires-et-les-cellules-de-veille-contribuent-a-lutter-contre-la-deperdition-scolaire\/#primaryimage","url":"https:\/\/dpress.ma\/fr\/wp-content\/uploads\/sites\/2\/2026\/05\/46-4.jpg","contentUrl":"https:\/\/dpress.ma\/fr\/wp-content\/uploads\/sites\/2\/2026\/05\/46-4.jpg","width":2539,"height":1594},{"@type":"BreadcrumbList","@id":"https:\/\/dpress.ma\/fr\/2026\/05\/12\/les-activites-parascolaires-et-les-cellules-de-veille-contribuent-a-lutter-contre-la-deperdition-scolaire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dpress.ma\/fr\/"},{"@type":"ListItem","position":2,"name":"Les activit\u00e9s parascolaires et les cellules de veille contribuent \u00e0 lutter contre la d\u00e9perdition scolaire"}]},{"@type":"WebSite","@id":"https:\/\/dpress.ma\/fr\/#website","url":"https:\/\/dpress.ma\/fr\/","name":"Dpress.ma\/fr","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dpress.ma\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/dpress.ma\/fr\/#\/schema\/person\/4898febf3ccd59e6578d838656a306a0","name":"Dpress.ma","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/72ecc30e9db047a2e0e7176561eb9d564ed77c8108376495b19bd8336405198a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/72ecc30e9db047a2e0e7176561eb9d564ed77c8108376495b19bd8336405198a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/72ecc30e9db047a2e0e7176561eb9d564ed77c8108376495b19bd8336405198a?s=96&d=mm&r=g","caption":"Dpress.ma"},"sameAs":["https:\/\/www.dpress.ma"],"url":"https:\/\/dpress.ma\/fr\/author\/dpress-ma\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/posts\/30708","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/comments?post=30708"}],"version-history":[{"count":1,"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/posts\/30708\/revisions"}],"predecessor-version":[{"id":30710,"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/posts\/30708\/revisions\/30710"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/media\/30709"}],"wp:attachment":[{"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/media?parent=30708"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/categories?post=30708"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/tags?post=30708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}