{"id":30689,"date":"2026-05-11T13:45:44","date_gmt":"2026-05-11T13:45:44","guid":{"rendered":"https:\/\/dpress.ma\/fr\/?p=30689"},"modified":"2026-05-11T13:45:49","modified_gmt":"2026-05-11T13:45:49","slug":"rabat-accueille-la-42e-reunion-pleniere-du-groupe-daction-financiere-du-moyen-orient-et-de-lafrique-du-nord","status":"publish","type":"post","link":"https:\/\/dpress.ma\/fr\/2026\/05\/11\/rabat-accueille-la-42e-reunion-pleniere-du-groupe-daction-financiere-du-moyen-orient-et-de-lafrique-du-nord\/","title":{"rendered":"Rabat accueille la 42e R\u00e9union pl\u00e9ni\u00e8re du Groupe d\u2019Action Financi\u00e8re du Moyen-Orient et de l\u2019Afrique du Nord"},"content":{"rendered":"\n<p>Dpress<\/p>\n\n\n\n<p>Les travaux de la 42e R\u00e9union pl\u00e9ni\u00e8re du Groupe d\u2019Action Financi\u00e8re du Moyen-Orient et de l\u2019Afrique du Nord (GAFIMOAN) ont d\u00e9marr\u00e9, lundi \u00e0 Rabat, avec la participation des chefs de d\u00e9l\u00e9gations des Etats membres, ainsi que des experts et observateurs de pays et d\u2019organisations r\u00e9gionales et internationales.<\/p>\n\n\n\n<p>Cette r\u00e9union, qui se poursuit jusqu\u2019au 13 mai, constitue un \u00e9v\u00e9nement r\u00e9gional majeur visant \u00e0 coordonner les efforts internationaux et r\u00e9gionaux en mati\u00e8re de lutte contre le blanchiment de capitaux, le financement du terrorisme et la prolif\u00e9ration des armes, ainsi qu\u2019\u00e0 prot\u00e9ger les syst\u00e8mes \u00e9conomiques et financiers de la r\u00e9gion contre les risques li\u00e9s \u00e0 ces crimes, indique un communiqu\u00e9 conjoint du d\u00e9partement du Chef du gouvernement et de l\u2019Autorit\u00e9 nationale du renseignement financier (ANRF).<\/p>\n\n\n\n<p>La r\u00e9union a d\u00e9but\u00e9 par les allocutions d\u2019ouverture de la ministre de l\u2019\u00c9conomie et des Finances, Nadia Fettah et du Pr\u00e9sident du Groupe et Secr\u00e9taire G\u00e9n\u00e9ral de la Commission Nationale de Lutte contre le Blanchiment de capitaux des \u00c9mirats Arabes Unis, Hamid Saif Al Zaabi.<\/p>\n\n\n\n<p>A cette occasion, ils ont mis l\u2019accent sur l\u2019importance de coordonner les efforts r\u00e9gionaux pour lutter contre les crimes financiers et le financement illicite, tout en insistant sur la n\u00e9cessit\u00e9 d\u2019une mise en \u0153uvre efficace des normes du GAFI, fond\u00e9es sur l\u2019approche par les risques, rel\u00e8ve le communiqu\u00e9.<\/p>\n\n\n\n<p>Dans ce contexte, Mme Fettah a r\u00e9affirm\u00e9 l\u2019engagement ferme du Royaume du Maroc \u00e0 d\u00e9velopper son dispositif national de lutte contre le blanchiment de capitaux et le financement du terrorisme, conform\u00e9ment aux standards internationaux, afin de prot\u00e9ger le syst\u00e8me financier national contre les risques \u00e9mergents.<\/p>\n\n\n\n<p>Pour sa part, M. Al Zaabi a pr\u00e9cis\u00e9 que la pr\u00e9sidence \u00e9miratie du Groupe pour l\u2019ann\u00e9e 2026 vise \u00e0 renforcer la position du GAFIMOAN au niveau international et \u00e0 intensifier la coordination avec les partenaires mondiaux.<\/p>\n\n\n\n<p>Les deux interventions se sont conclues par un appel aux \u00e9tats membres \u00e0 renforcer l\u2019\u00e9change d\u2019expertises et \u00e0 d\u00e9velopper des m\u00e9canismes de lutte contre les crimes financiers \u00e9mergeants, afin de garantir la stabilit\u00e9 et la durabilit\u00e9 du syst\u00e8me financier dans la r\u00e9gion, note le communiqu\u00e9.<\/p>\n\n\n\n<p>Les travaux de cette rencontre s\u2019articulent autour de la discussion et de l\u2019adoption des rapports de suivi renforc\u00e9 de plusieurs \u00e9tats membres, ainsi que sur l\u2019\u00e9valuation des mesures prises pour rem\u00e9dier aux lacunes relev\u00e9es dans les rapports d\u2019\u00e9valuation mutuelle, fait savoir la m\u00eame source.<\/p>\n\n\n\n<p>Ils visent \u00e9galement \u00e0 renforcer la coordination r\u00e9gionale et \u00e0 \u00e9changer des meilleures pratiques en mati\u00e8re de lutte contre le blanchiment de capitaux, le financement du terrorisme et le financement de la prolif\u00e9ration des armes.<\/p>\n\n\n\n<p>Par ailleurs, la r\u00e9union porte sur l\u2019examen des questions li\u00e9es aux comp\u00e9tences du Groupe et sur l\u2019adoption de son plan d\u2019action au titre de l\u2019ann\u00e9e 2027, conclut le communiqu\u00e9.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dpress Les travaux de la 42e R\u00e9union pl\u00e9ni\u00e8re du Groupe d\u2019Action Financi\u00e8re du Moyen-Orient et de l\u2019Afrique du Nord (GAFIMOAN) ont d\u00e9marr\u00e9, lundi \u00e0 Rabat, avec la participation des chefs de d\u00e9l\u00e9gations des Etats membres, ainsi que des experts et observateurs de pays et d\u2019organisations r\u00e9gionales et internationales. Cette r\u00e9union, qui se poursuit jusqu\u2019au 13 &hellip;<\/p>\n","protected":false},"author":2,"featured_media":30690,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[],"class_list":["post-30689","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rabat accueille la 42e R\u00e9union pl\u00e9ni\u00e8re du Groupe d\u2019Action Financi\u00e8re du Moyen-Orient et de l\u2019Afrique du Nord - Dpress.ma\/fr<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dpress.ma\/fr\/2026\/05\/11\/rabat-accueille-la-42e-reunion-pleniere-du-groupe-daction-financiere-du-moyen-orient-et-de-lafrique-du-nord\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rabat accueille la 42e R\u00e9union pl\u00e9ni\u00e8re du Groupe d\u2019Action Financi\u00e8re du Moyen-Orient et de l\u2019Afrique du Nord - Dpress.ma\/fr\" \/>\n<meta property=\"og:description\" content=\"Dpress Les travaux de la 42e R\u00e9union pl\u00e9ni\u00e8re du Groupe d\u2019Action Financi\u00e8re du Moyen-Orient et de l\u2019Afrique du Nord (GAFIMOAN) ont d\u00e9marr\u00e9, lundi \u00e0 Rabat, avec la participation des chefs de d\u00e9l\u00e9gations des Etats membres, ainsi que des experts et observateurs de pays et d\u2019organisations r\u00e9gionales et internationales. Cette r\u00e9union, qui se poursuit jusqu\u2019au 13 &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dpress.ma\/fr\/2026\/05\/11\/rabat-accueille-la-42e-reunion-pleniere-du-groupe-daction-financiere-du-moyen-orient-et-de-lafrique-du-nord\/\" \/>\n<meta property=\"og:site_name\" content=\"Dpress.ma\/fr\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-11T13:45:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-11T13:45:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dpress.ma\/fr\/wp-content\/uploads\/sites\/2\/2026\/05\/82-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2539\" \/>\n\t<meta property=\"og:image:height\" content=\"1594\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dpress.ma\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dpress.ma\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/11\\\/rabat-accueille-la-42e-reunion-pleniere-du-groupe-daction-financiere-du-moyen-orient-et-de-lafrique-du-nord\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/11\\\/rabat-accueille-la-42e-reunion-pleniere-du-groupe-daction-financiere-du-moyen-orient-et-de-lafrique-du-nord\\\/\"},\"author\":{\"name\":\"Dpress.ma\",\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/#\\\/schema\\\/person\\\/4898febf3ccd59e6578d838656a306a0\"},\"headline\":\"Rabat accueille la 42e R\u00e9union pl\u00e9ni\u00e8re du Groupe d\u2019Action Financi\u00e8re du Moyen-Orient et de l\u2019Afrique du Nord\",\"datePublished\":\"2026-05-11T13:45:44+00:00\",\"dateModified\":\"2026-05-11T13:45:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/11\\\/rabat-accueille-la-42e-reunion-pleniere-du-groupe-daction-financiere-du-moyen-orient-et-de-lafrique-du-nord\\\/\"},\"wordCount\":534,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/11\\\/rabat-accueille-la-42e-reunion-pleniere-du-groupe-daction-financiere-du-moyen-orient-et-de-lafrique-du-nord\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/05\\\/82-1.jpg\",\"articleSection\":[\"\u00c9conomie\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/11\\\/rabat-accueille-la-42e-reunion-pleniere-du-groupe-daction-financiere-du-moyen-orient-et-de-lafrique-du-nord\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/11\\\/rabat-accueille-la-42e-reunion-pleniere-du-groupe-daction-financiere-du-moyen-orient-et-de-lafrique-du-nord\\\/\",\"url\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/11\\\/rabat-accueille-la-42e-reunion-pleniere-du-groupe-daction-financiere-du-moyen-orient-et-de-lafrique-du-nord\\\/\",\"name\":\"Rabat accueille la 42e R\u00e9union pl\u00e9ni\u00e8re du Groupe d\u2019Action Financi\u00e8re du Moyen-Orient et de l\u2019Afrique du Nord - Dpress.ma\\\/fr\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/11\\\/rabat-accueille-la-42e-reunion-pleniere-du-groupe-daction-financiere-du-moyen-orient-et-de-lafrique-du-nord\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/11\\\/rabat-accueille-la-42e-reunion-pleniere-du-groupe-daction-financiere-du-moyen-orient-et-de-lafrique-du-nord\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/05\\\/82-1.jpg\",\"datePublished\":\"2026-05-11T13:45:44+00:00\",\"dateModified\":\"2026-05-11T13:45:49+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/#\\\/schema\\\/person\\\/4898febf3ccd59e6578d838656a306a0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/11\\\/rabat-accueille-la-42e-reunion-pleniere-du-groupe-daction-financiere-du-moyen-orient-et-de-lafrique-du-nord\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/11\\\/rabat-accueille-la-42e-reunion-pleniere-du-groupe-daction-financiere-du-moyen-orient-et-de-lafrique-du-nord\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/11\\\/rabat-accueille-la-42e-reunion-pleniere-du-groupe-daction-financiere-du-moyen-orient-et-de-lafrique-du-nord\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/05\\\/82-1.jpg\",\"contentUrl\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/05\\\/82-1.jpg\",\"width\":2539,\"height\":1594},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/11\\\/rabat-accueille-la-42e-reunion-pleniere-du-groupe-daction-financiere-du-moyen-orient-et-de-lafrique-du-nord\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rabat accueille la 42e R\u00e9union pl\u00e9ni\u00e8re du Groupe d\u2019Action Financi\u00e8re du Moyen-Orient et de l\u2019Afrique du Nord\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/\",\"name\":\"Dpress.ma\\\/fr\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/#\\\/schema\\\/person\\\/4898febf3ccd59e6578d838656a306a0\",\"name\":\"Dpress.ma\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72ecc30e9db047a2e0e7176561eb9d564ed77c8108376495b19bd8336405198a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72ecc30e9db047a2e0e7176561eb9d564ed77c8108376495b19bd8336405198a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72ecc30e9db047a2e0e7176561eb9d564ed77c8108376495b19bd8336405198a?s=96&d=mm&r=g\",\"caption\":\"Dpress.ma\"},\"sameAs\":[\"https:\\\/\\\/www.dpress.ma\"],\"url\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/author\\\/dpress-ma\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rabat accueille la 42e R\u00e9union pl\u00e9ni\u00e8re du Groupe d\u2019Action Financi\u00e8re du Moyen-Orient et de l\u2019Afrique du Nord - Dpress.ma\/fr","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dpress.ma\/fr\/2026\/05\/11\/rabat-accueille-la-42e-reunion-pleniere-du-groupe-daction-financiere-du-moyen-orient-et-de-lafrique-du-nord\/","og_locale":"fr_FR","og_type":"article","og_title":"Rabat accueille la 42e R\u00e9union pl\u00e9ni\u00e8re du Groupe d\u2019Action Financi\u00e8re du Moyen-Orient et de l\u2019Afrique du Nord - Dpress.ma\/fr","og_description":"Dpress Les travaux de la 42e R\u00e9union pl\u00e9ni\u00e8re du Groupe d\u2019Action Financi\u00e8re du Moyen-Orient et de l\u2019Afrique du Nord (GAFIMOAN) ont d\u00e9marr\u00e9, lundi \u00e0 Rabat, avec la participation des chefs de d\u00e9l\u00e9gations des Etats membres, ainsi que des experts et observateurs de pays et d\u2019organisations r\u00e9gionales et internationales. Cette r\u00e9union, qui se poursuit jusqu\u2019au 13 &hellip;","og_url":"https:\/\/dpress.ma\/fr\/2026\/05\/11\/rabat-accueille-la-42e-reunion-pleniere-du-groupe-daction-financiere-du-moyen-orient-et-de-lafrique-du-nord\/","og_site_name":"Dpress.ma\/fr","article_published_time":"2026-05-11T13:45:44+00:00","article_modified_time":"2026-05-11T13:45:49+00:00","og_image":[{"width":2539,"height":1594,"url":"https:\/\/dpress.ma\/fr\/wp-content\/uploads\/sites\/2\/2026\/05\/82-1.jpg","type":"image\/jpeg"}],"author":"Dpress.ma","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Dpress.ma","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dpress.ma\/fr\/2026\/05\/11\/rabat-accueille-la-42e-reunion-pleniere-du-groupe-daction-financiere-du-moyen-orient-et-de-lafrique-du-nord\/#article","isPartOf":{"@id":"https:\/\/dpress.ma\/fr\/2026\/05\/11\/rabat-accueille-la-42e-reunion-pleniere-du-groupe-daction-financiere-du-moyen-orient-et-de-lafrique-du-nord\/"},"author":{"name":"Dpress.ma","@id":"https:\/\/dpress.ma\/fr\/#\/schema\/person\/4898febf3ccd59e6578d838656a306a0"},"headline":"Rabat accueille la 42e R\u00e9union pl\u00e9ni\u00e8re du Groupe d\u2019Action Financi\u00e8re du Moyen-Orient et de l\u2019Afrique du Nord","datePublished":"2026-05-11T13:45:44+00:00","dateModified":"2026-05-11T13:45:49+00:00","mainEntityOfPage":{"@id":"https:\/\/dpress.ma\/fr\/2026\/05\/11\/rabat-accueille-la-42e-reunion-pleniere-du-groupe-daction-financiere-du-moyen-orient-et-de-lafrique-du-nord\/"},"wordCount":534,"commentCount":0,"image":{"@id":"https:\/\/dpress.ma\/fr\/2026\/05\/11\/rabat-accueille-la-42e-reunion-pleniere-du-groupe-daction-financiere-du-moyen-orient-et-de-lafrique-du-nord\/#primaryimage"},"thumbnailUrl":"https:\/\/dpress.ma\/fr\/wp-content\/uploads\/sites\/2\/2026\/05\/82-1.jpg","articleSection":["\u00c9conomie"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dpress.ma\/fr\/2026\/05\/11\/rabat-accueille-la-42e-reunion-pleniere-du-groupe-daction-financiere-du-moyen-orient-et-de-lafrique-du-nord\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dpress.ma\/fr\/2026\/05\/11\/rabat-accueille-la-42e-reunion-pleniere-du-groupe-daction-financiere-du-moyen-orient-et-de-lafrique-du-nord\/","url":"https:\/\/dpress.ma\/fr\/2026\/05\/11\/rabat-accueille-la-42e-reunion-pleniere-du-groupe-daction-financiere-du-moyen-orient-et-de-lafrique-du-nord\/","name":"Rabat accueille la 42e R\u00e9union pl\u00e9ni\u00e8re du Groupe d\u2019Action Financi\u00e8re du Moyen-Orient et de l\u2019Afrique du Nord - Dpress.ma\/fr","isPartOf":{"@id":"https:\/\/dpress.ma\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dpress.ma\/fr\/2026\/05\/11\/rabat-accueille-la-42e-reunion-pleniere-du-groupe-daction-financiere-du-moyen-orient-et-de-lafrique-du-nord\/#primaryimage"},"image":{"@id":"https:\/\/dpress.ma\/fr\/2026\/05\/11\/rabat-accueille-la-42e-reunion-pleniere-du-groupe-daction-financiere-du-moyen-orient-et-de-lafrique-du-nord\/#primaryimage"},"thumbnailUrl":"https:\/\/dpress.ma\/fr\/wp-content\/uploads\/sites\/2\/2026\/05\/82-1.jpg","datePublished":"2026-05-11T13:45:44+00:00","dateModified":"2026-05-11T13:45:49+00:00","author":{"@id":"https:\/\/dpress.ma\/fr\/#\/schema\/person\/4898febf3ccd59e6578d838656a306a0"},"breadcrumb":{"@id":"https:\/\/dpress.ma\/fr\/2026\/05\/11\/rabat-accueille-la-42e-reunion-pleniere-du-groupe-daction-financiere-du-moyen-orient-et-de-lafrique-du-nord\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dpress.ma\/fr\/2026\/05\/11\/rabat-accueille-la-42e-reunion-pleniere-du-groupe-daction-financiere-du-moyen-orient-et-de-lafrique-du-nord\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dpress.ma\/fr\/2026\/05\/11\/rabat-accueille-la-42e-reunion-pleniere-du-groupe-daction-financiere-du-moyen-orient-et-de-lafrique-du-nord\/#primaryimage","url":"https:\/\/dpress.ma\/fr\/wp-content\/uploads\/sites\/2\/2026\/05\/82-1.jpg","contentUrl":"https:\/\/dpress.ma\/fr\/wp-content\/uploads\/sites\/2\/2026\/05\/82-1.jpg","width":2539,"height":1594},{"@type":"BreadcrumbList","@id":"https:\/\/dpress.ma\/fr\/2026\/05\/11\/rabat-accueille-la-42e-reunion-pleniere-du-groupe-daction-financiere-du-moyen-orient-et-de-lafrique-du-nord\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dpress.ma\/fr\/"},{"@type":"ListItem","position":2,"name":"Rabat accueille la 42e R\u00e9union pl\u00e9ni\u00e8re du Groupe d\u2019Action Financi\u00e8re du Moyen-Orient et de l\u2019Afrique du Nord"}]},{"@type":"WebSite","@id":"https:\/\/dpress.ma\/fr\/#website","url":"https:\/\/dpress.ma\/fr\/","name":"Dpress.ma\/fr","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dpress.ma\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/dpress.ma\/fr\/#\/schema\/person\/4898febf3ccd59e6578d838656a306a0","name":"Dpress.ma","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/72ecc30e9db047a2e0e7176561eb9d564ed77c8108376495b19bd8336405198a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/72ecc30e9db047a2e0e7176561eb9d564ed77c8108376495b19bd8336405198a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/72ecc30e9db047a2e0e7176561eb9d564ed77c8108376495b19bd8336405198a?s=96&d=mm&r=g","caption":"Dpress.ma"},"sameAs":["https:\/\/www.dpress.ma"],"url":"https:\/\/dpress.ma\/fr\/author\/dpress-ma\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/posts\/30689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/comments?post=30689"}],"version-history":[{"count":1,"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/posts\/30689\/revisions"}],"predecessor-version":[{"id":30691,"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/posts\/30689\/revisions\/30691"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/media\/30690"}],"wp:attachment":[{"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/media?parent=30689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/categories?post=30689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/tags?post=30689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}