{"id":30634,"date":"2026-05-11T11:08:46","date_gmt":"2026-05-11T11:08:46","guid":{"rendered":"https:\/\/dpress.ma\/fr\/?p=30634"},"modified":"2026-05-11T11:08:49","modified_gmt":"2026-05-11T11:08:49","slug":"essaouira-cloture-de-la-8e-edition-du-congres-international-de-larganier","status":"publish","type":"post","link":"https:\/\/dpress.ma\/fr\/2026\/05\/11\/essaouira-cloture-de-la-8e-edition-du-congres-international-de-larganier\/","title":{"rendered":"Essaouira : Cl\u00f4ture de la 8e \u00e9dition du Congr\u00e8s International de l\u2019Arganier"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Dpress<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les travaux de la 8e \u00e9dition du Congr\u00e8s International de l\u2019Arganier ont pris fin, dimanche \u00e0 Essaouira, apr\u00e8s trois journ\u00e9es d\u2019\u00e9changes scientifiques et institutionnels consacr\u00e9s aux enjeux de pr\u00e9servation et de valorisation durable de l\u2019arganier.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Plac\u00e9 sous le Haut Patronage de Sa Majest\u00e9 le Roi Mohammed VI, ce congr\u00e8s d\u2019envergure, organis\u00e9 sous le th\u00e8me \u201cDe l\u2019Arganeraie \u00e0 l\u2019Arganiculture : l\u2019Arganier, pilier de la r\u00e9silience hydrique des \u00e9cosyst\u00e8mes, des territoires et des communaut\u00e9s\u201d, s\u2019est impos\u00e9 comme une plateforme de r\u00e9f\u00e9rence d\u00e9di\u00e9e au partage d\u2019expertises et \u00e0 la promotion de l\u2019innovation autour de cette fili\u00e8re strat\u00e9gique.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cette \u00e9dition, organis\u00e9e par l\u2019Agence Nationale pour le D\u00e9veloppement des Zones Oasiennes et de l\u2019Arganier (ANDZOA), en partenariat avec l\u2019Institut National de la Recherche Agronomique (INRA), l\u2019Agence Nationale des Eaux et For\u00eats (ANEF) et la F\u00e9d\u00e9ration Interprofessionnelle de la Fili\u00e8re de l\u2019Argane (FIFARGANE), a connu la participation de pr\u00e8s de 500 congressistes et la pr\u00e9sentation de plus de 130 communications scientifiques portant sur les dimensions environnementales, \u00e9conomiques, sociales et technologiques de l\u2019arganier.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pr\u00e9sid\u00e9e par le ministre de l\u2019Agriculture, de la P\u00eache Maritime, du D\u00e9veloppement Rural et des Eaux et For\u00eats, Ahmed El Bouari, la c\u00e9r\u00e9monie de cl\u00f4ture a \u00e9t\u00e9 marqu\u00e9e par la signature de plusieurs conventions de partenariat visant \u00e0 renforcer la recherche scientifique, promouvoir l\u2019innovation et soutenir le d\u00e9veloppement durable de la fili\u00e8re de l\u2019arganier.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ainsi, l\u2019ANDZOA a sign\u00e9 des conventions de partenariat avec respectivement l\u2019INRA, l\u2019Institut Africain de la Nutrition des Plantes (APNI) et la soci\u00e9t\u00e9 Managem, portant notamment sur le d\u00e9veloppement de programmes de recherche appliqu\u00e9e, le renforcement des capacit\u00e9s techniques et scientifiques, l\u2019am\u00e9lioration des pratiques li\u00e9es \u00e0 l\u2019arganiculture ainsi que la promotion de solutions innovantes en faveur de la durabilit\u00e9 et de la r\u00e9silience de l\u2019\u00e9cosyst\u00e8me de l\u2019arganier.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La c\u00e9r\u00e9monie de cl\u00f4ture a \u00e9galement \u00e9t\u00e9 ponctu\u00e9e par la remise des prix \u201cJeunes chercheurs\u201d dans la cat\u00e9gorie master\/m\u00e9moire d\u2019ing\u00e9nieur, attribu\u00e9s respectivement \u00e0 Bounasser Bouchra (1er prix), Nouhaila Menan (2e prix) et Saida Dakir (3e prix).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans la cat\u00e9gorie th\u00e8se de doctorat, le 1er prix a \u00e9t\u00e9 d\u00e9cern\u00e9 \u00e0 Mohamed Mouafik, suivi de Oussama Bayssi (2e prix) et Abdelmoiz El Faqer (3e prix).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Des distinctions ont aussi \u00e9t\u00e9 remises dans le cadre des \u201cDoctoriales de la Chaire ICESCO de l\u2019Arganier\u201d, avec un 1er prix attribu\u00e9 \u00e0 Laila Amjlef, un 2e prix \u00e0 Amina Braimi et un 3e prix \u00e0 Boujemaa Fassih.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Par ailleurs, la directrice de l\u2019INRA, Lamiae Ghaouti, a pr\u00e9sent\u00e9 les principales recommandations issues des diff\u00e9rentes sessions scientifiques du congr\u00e8s, structur\u00e9es autour de quatre axes majeurs portant sur la biodiversit\u00e9 et l\u2019\u00e9cologie de l\u2019arganier, l\u2019arganiculture, la valorisation des produits d\u00e9riv\u00e9s ainsi que les dimensions socio-\u00e9conomiques li\u00e9es \u00e0 cet \u00e9cosyst\u00e8me.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans ces recommandations, les participants ont soulign\u00e9 la n\u00e9cessit\u00e9 de passer d\u2019une gestion foresti\u00e8re traditionnelle \u00e0 une v\u00e9ritable arboriculture moderne, \u00e0 travers l\u2019adoption de vari\u00e9t\u00e9s inscrites au catalogue officiel et multipli\u00e9es par clonage afin de garantir productivit\u00e9 et qualit\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mettant en avant les avanc\u00e9es r\u00e9alis\u00e9es dans les domaines de la biotechnologie et de la g\u00e9nomique, avec le s\u00e9quen\u00e7age de l\u2019arganier par l\u2019INRA ayant permis l\u2019identification de pr\u00e8s de 35.000 g\u00e8nes, ainsi que l\u2019am\u00e9lioration des itin\u00e9raires techniques et de la qualit\u00e9 de l\u2019huile d\u2019argan, les participants ont insist\u00e9 sur l\u2019importance de l\u2019exploitation des sous-produits de l\u2019arganier afin de renforcer la rentabilit\u00e9 de la fili\u00e8re et de favoriser une meilleure int\u00e9gration des agriculteurs, des femmes et des jeunes dans une approche globale de l\u2019agro\u00e9cosyst\u00e8me.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ils ont, en outre, plaid\u00e9 pour le renforcement des syst\u00e8mes agroforestiers, la multiplication des initiatives de type SIPAM et la valorisation du potentiel de s\u00e9questration du carbone par l\u2019arganier, tout en insistant sur l\u2019importance de poursuivre les efforts de soutien \u00e0 la recherche scientifique et \u00e0 l\u2019innovation, notamment en faveur des jeunes chercheurs, afin d\u2019accompagner le d\u00e9veloppement durable et la r\u00e9silience de la fili\u00e8re.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 travers cette nouvelle \u00e9dition, le Congr\u00e8s International de l\u2019Arganier, v\u00e9ritable carrefour mondial de r\u00e9f\u00e9rence pour la recherche sur l\u2019arganier, confirme une fois encore son positionnement en tant que plateforme internationale d\u2019\u00e9change, de r\u00e9flexion et de prospective, contribuant \u00e0 accompagner la dynamique de d\u00e9veloppement de la fili\u00e8re dans le cadre de la strat\u00e9gie \u201cG\u00e9n\u00e9ration Green\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Au-del\u00e0 du partage scientifique, ce rendez-vous biennal contribue \u00e0 d\u00e9finir les strat\u00e9gies de d\u00e9veloppement durable de la fili\u00e8re, l\u2019ultime finalit\u00e9 \u00e9tant de concilier innovation technique, pr\u00e9servation de l\u2019\u00e9cosyst\u00e8me et valorisation socio-\u00e9conomique de l\u2019Arganeraie.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dpress Les travaux de la 8e \u00e9dition du Congr\u00e8s International de l\u2019Arganier ont pris fin, dimanche \u00e0 Essaouira, apr\u00e8s trois journ\u00e9es d\u2019\u00e9changes scientifiques et institutionnels consacr\u00e9s aux enjeux de pr\u00e9servation et de valorisation durable de l\u2019arganier. Plac\u00e9 sous le Haut Patronage de Sa Majest\u00e9 le Roi Mohammed VI, ce congr\u00e8s d\u2019envergure, organis\u00e9 sous le th\u00e8me &hellip;<\/p>\n","protected":false},"author":2,"featured_media":30635,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[],"class_list":["post-30634","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Essaouira : Cl\u00f4ture de la 8e \u00e9dition du Congr\u00e8s International de l\u2019Arganier - Dpress.ma\/fr<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dpress.ma\/fr\/2026\/05\/11\/essaouira-cloture-de-la-8e-edition-du-congres-international-de-larganier\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Essaouira : Cl\u00f4ture de la 8e \u00e9dition du Congr\u00e8s International de l\u2019Arganier - Dpress.ma\/fr\" \/>\n<meta property=\"og:description\" content=\"Dpress Les travaux de la 8e \u00e9dition du Congr\u00e8s International de l\u2019Arganier ont pris fin, dimanche \u00e0 Essaouira, apr\u00e8s trois journ\u00e9es d\u2019\u00e9changes scientifiques et institutionnels consacr\u00e9s aux enjeux de pr\u00e9servation et de valorisation durable de l\u2019arganier. Plac\u00e9 sous le Haut Patronage de Sa Majest\u00e9 le Roi Mohammed VI, ce congr\u00e8s d\u2019envergure, organis\u00e9 sous le th\u00e8me &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dpress.ma\/fr\/2026\/05\/11\/essaouira-cloture-de-la-8e-edition-du-congres-international-de-larganier\/\" \/>\n<meta property=\"og:site_name\" content=\"Dpress.ma\/fr\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-11T11:08:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-11T11:08:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dpress.ma\/fr\/wp-content\/uploads\/sites\/2\/2026\/05\/63-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2539\" \/>\n\t<meta property=\"og:image:height\" content=\"1594\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dpress.ma\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dpress.ma\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/11\\\/essaouira-cloture-de-la-8e-edition-du-congres-international-de-larganier\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/11\\\/essaouira-cloture-de-la-8e-edition-du-congres-international-de-larganier\\\/\"},\"author\":{\"name\":\"Dpress.ma\",\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/#\\\/schema\\\/person\\\/4898febf3ccd59e6578d838656a306a0\"},\"headline\":\"Essaouira : Cl\u00f4ture de la 8e \u00e9dition du Congr\u00e8s International de l\u2019Arganier\",\"datePublished\":\"2026-05-11T11:08:46+00:00\",\"dateModified\":\"2026-05-11T11:08:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/11\\\/essaouira-cloture-de-la-8e-edition-du-congres-international-de-larganier\\\/\"},\"wordCount\":863,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/11\\\/essaouira-cloture-de-la-8e-edition-du-congres-international-de-larganier\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/05\\\/63-3.jpg\",\"articleSection\":[\"\u00c9conomie\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/11\\\/essaouira-cloture-de-la-8e-edition-du-congres-international-de-larganier\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/11\\\/essaouira-cloture-de-la-8e-edition-du-congres-international-de-larganier\\\/\",\"url\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/11\\\/essaouira-cloture-de-la-8e-edition-du-congres-international-de-larganier\\\/\",\"name\":\"Essaouira : Cl\u00f4ture de la 8e \u00e9dition du Congr\u00e8s International de l\u2019Arganier - Dpress.ma\\\/fr\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/11\\\/essaouira-cloture-de-la-8e-edition-du-congres-international-de-larganier\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/11\\\/essaouira-cloture-de-la-8e-edition-du-congres-international-de-larganier\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/05\\\/63-3.jpg\",\"datePublished\":\"2026-05-11T11:08:46+00:00\",\"dateModified\":\"2026-05-11T11:08:49+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/#\\\/schema\\\/person\\\/4898febf3ccd59e6578d838656a306a0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/11\\\/essaouira-cloture-de-la-8e-edition-du-congres-international-de-larganier\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/11\\\/essaouira-cloture-de-la-8e-edition-du-congres-international-de-larganier\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/11\\\/essaouira-cloture-de-la-8e-edition-du-congres-international-de-larganier\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/05\\\/63-3.jpg\",\"contentUrl\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/05\\\/63-3.jpg\",\"width\":2539,\"height\":1594},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/11\\\/essaouira-cloture-de-la-8e-edition-du-congres-international-de-larganier\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Essaouira : Cl\u00f4ture de la 8e \u00e9dition du Congr\u00e8s International de l\u2019Arganier\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/\",\"name\":\"Dpress.ma\\\/fr\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/#\\\/schema\\\/person\\\/4898febf3ccd59e6578d838656a306a0\",\"name\":\"Dpress.ma\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72ecc30e9db047a2e0e7176561eb9d564ed77c8108376495b19bd8336405198a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72ecc30e9db047a2e0e7176561eb9d564ed77c8108376495b19bd8336405198a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72ecc30e9db047a2e0e7176561eb9d564ed77c8108376495b19bd8336405198a?s=96&d=mm&r=g\",\"caption\":\"Dpress.ma\"},\"sameAs\":[\"https:\\\/\\\/www.dpress.ma\"],\"url\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/author\\\/dpress-ma\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Essaouira : Cl\u00f4ture de la 8e \u00e9dition du Congr\u00e8s International de l\u2019Arganier - Dpress.ma\/fr","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dpress.ma\/fr\/2026\/05\/11\/essaouira-cloture-de-la-8e-edition-du-congres-international-de-larganier\/","og_locale":"fr_FR","og_type":"article","og_title":"Essaouira : Cl\u00f4ture de la 8e \u00e9dition du Congr\u00e8s International de l\u2019Arganier - Dpress.ma\/fr","og_description":"Dpress Les travaux de la 8e \u00e9dition du Congr\u00e8s International de l\u2019Arganier ont pris fin, dimanche \u00e0 Essaouira, apr\u00e8s trois journ\u00e9es d\u2019\u00e9changes scientifiques et institutionnels consacr\u00e9s aux enjeux de pr\u00e9servation et de valorisation durable de l\u2019arganier. Plac\u00e9 sous le Haut Patronage de Sa Majest\u00e9 le Roi Mohammed VI, ce congr\u00e8s d\u2019envergure, organis\u00e9 sous le th\u00e8me &hellip;","og_url":"https:\/\/dpress.ma\/fr\/2026\/05\/11\/essaouira-cloture-de-la-8e-edition-du-congres-international-de-larganier\/","og_site_name":"Dpress.ma\/fr","article_published_time":"2026-05-11T11:08:46+00:00","article_modified_time":"2026-05-11T11:08:49+00:00","og_image":[{"width":2539,"height":1594,"url":"https:\/\/dpress.ma\/fr\/wp-content\/uploads\/sites\/2\/2026\/05\/63-3.jpg","type":"image\/jpeg"}],"author":"Dpress.ma","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Dpress.ma","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dpress.ma\/fr\/2026\/05\/11\/essaouira-cloture-de-la-8e-edition-du-congres-international-de-larganier\/#article","isPartOf":{"@id":"https:\/\/dpress.ma\/fr\/2026\/05\/11\/essaouira-cloture-de-la-8e-edition-du-congres-international-de-larganier\/"},"author":{"name":"Dpress.ma","@id":"https:\/\/dpress.ma\/fr\/#\/schema\/person\/4898febf3ccd59e6578d838656a306a0"},"headline":"Essaouira : Cl\u00f4ture de la 8e \u00e9dition du Congr\u00e8s International de l\u2019Arganier","datePublished":"2026-05-11T11:08:46+00:00","dateModified":"2026-05-11T11:08:49+00:00","mainEntityOfPage":{"@id":"https:\/\/dpress.ma\/fr\/2026\/05\/11\/essaouira-cloture-de-la-8e-edition-du-congres-international-de-larganier\/"},"wordCount":863,"commentCount":0,"image":{"@id":"https:\/\/dpress.ma\/fr\/2026\/05\/11\/essaouira-cloture-de-la-8e-edition-du-congres-international-de-larganier\/#primaryimage"},"thumbnailUrl":"https:\/\/dpress.ma\/fr\/wp-content\/uploads\/sites\/2\/2026\/05\/63-3.jpg","articleSection":["\u00c9conomie"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dpress.ma\/fr\/2026\/05\/11\/essaouira-cloture-de-la-8e-edition-du-congres-international-de-larganier\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dpress.ma\/fr\/2026\/05\/11\/essaouira-cloture-de-la-8e-edition-du-congres-international-de-larganier\/","url":"https:\/\/dpress.ma\/fr\/2026\/05\/11\/essaouira-cloture-de-la-8e-edition-du-congres-international-de-larganier\/","name":"Essaouira : Cl\u00f4ture de la 8e \u00e9dition du Congr\u00e8s International de l\u2019Arganier - Dpress.ma\/fr","isPartOf":{"@id":"https:\/\/dpress.ma\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dpress.ma\/fr\/2026\/05\/11\/essaouira-cloture-de-la-8e-edition-du-congres-international-de-larganier\/#primaryimage"},"image":{"@id":"https:\/\/dpress.ma\/fr\/2026\/05\/11\/essaouira-cloture-de-la-8e-edition-du-congres-international-de-larganier\/#primaryimage"},"thumbnailUrl":"https:\/\/dpress.ma\/fr\/wp-content\/uploads\/sites\/2\/2026\/05\/63-3.jpg","datePublished":"2026-05-11T11:08:46+00:00","dateModified":"2026-05-11T11:08:49+00:00","author":{"@id":"https:\/\/dpress.ma\/fr\/#\/schema\/person\/4898febf3ccd59e6578d838656a306a0"},"breadcrumb":{"@id":"https:\/\/dpress.ma\/fr\/2026\/05\/11\/essaouira-cloture-de-la-8e-edition-du-congres-international-de-larganier\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dpress.ma\/fr\/2026\/05\/11\/essaouira-cloture-de-la-8e-edition-du-congres-international-de-larganier\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dpress.ma\/fr\/2026\/05\/11\/essaouira-cloture-de-la-8e-edition-du-congres-international-de-larganier\/#primaryimage","url":"https:\/\/dpress.ma\/fr\/wp-content\/uploads\/sites\/2\/2026\/05\/63-3.jpg","contentUrl":"https:\/\/dpress.ma\/fr\/wp-content\/uploads\/sites\/2\/2026\/05\/63-3.jpg","width":2539,"height":1594},{"@type":"BreadcrumbList","@id":"https:\/\/dpress.ma\/fr\/2026\/05\/11\/essaouira-cloture-de-la-8e-edition-du-congres-international-de-larganier\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dpress.ma\/fr\/"},{"@type":"ListItem","position":2,"name":"Essaouira : Cl\u00f4ture de la 8e \u00e9dition du Congr\u00e8s International de l\u2019Arganier"}]},{"@type":"WebSite","@id":"https:\/\/dpress.ma\/fr\/#website","url":"https:\/\/dpress.ma\/fr\/","name":"Dpress.ma\/fr","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dpress.ma\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/dpress.ma\/fr\/#\/schema\/person\/4898febf3ccd59e6578d838656a306a0","name":"Dpress.ma","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/72ecc30e9db047a2e0e7176561eb9d564ed77c8108376495b19bd8336405198a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/72ecc30e9db047a2e0e7176561eb9d564ed77c8108376495b19bd8336405198a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/72ecc30e9db047a2e0e7176561eb9d564ed77c8108376495b19bd8336405198a?s=96&d=mm&r=g","caption":"Dpress.ma"},"sameAs":["https:\/\/www.dpress.ma"],"url":"https:\/\/dpress.ma\/fr\/author\/dpress-ma\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/posts\/30634","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/comments?post=30634"}],"version-history":[{"count":1,"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/posts\/30634\/revisions"}],"predecessor-version":[{"id":30636,"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/posts\/30634\/revisions\/30636"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/media\/30635"}],"wp:attachment":[{"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/media?parent=30634"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/categories?post=30634"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/tags?post=30634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}