{"id":30631,"date":"2026-05-11T11:07:21","date_gmt":"2026-05-11T11:07:21","guid":{"rendered":"https:\/\/dpress.ma\/fr\/?p=30631"},"modified":"2026-05-11T11:07:25","modified_gmt":"2026-05-11T11:07:25","slug":"essaouira-larganier-un-levier-strategique-pour-la-resilience-des-territoires-arides","status":"publish","type":"post","link":"https:\/\/dpress.ma\/fr\/2026\/05\/11\/essaouira-larganier-un-levier-strategique-pour-la-resilience-des-territoires-arides\/","title":{"rendered":"Essaouira : L\u2019arganier, un levier strat\u00e9gique pour la r\u00e9silience des territoires arides"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Dpress<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019arganier repr\u00e9sente un levier strat\u00e9gique pour la r\u00e9silience des territoires arides et semi-arides, a soulign\u00e9, dimanche \u00e0 Essaouira, Rachid Mentag, chercheur \u00e0 l\u2019Institut national de la recherche agronomique (INRA).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lors d\u2019un panel organis\u00e9 dans le cadre de la 8e \u00e9dition du Congr\u00e8s International de l\u2019Arganier, sous le th\u00e8me \u201cArganiculture, biotechnologies et am\u00e9lioration g\u00e9n\u00e9tique\u201d, M. Mentag a relev\u00e9 que l\u2019arganier, cette esp\u00e8ce foresti\u00e8re embl\u00e9matique du Maroc, repr\u00e9sente un levier strat\u00e9gique pour la pr\u00e9servation des ressources naturelles, le maintien de la biodiversit\u00e9 ainsi que le d\u00e9veloppement socio-\u00e9conomique des populations locales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ce chercheur a aussi soulign\u00e9 la n\u00e9cessit\u00e9 du d\u00e9veloppement d\u2019une arganiculture moderne, durable et scientifiquement fond\u00e9e, pour faire face aux effets combin\u00e9s du changement climatique, de la pression anthropique et de la faible r\u00e9g\u00e9n\u00e9ration naturelle.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ce panel a aussi \u00e9t\u00e9 l\u2019occasion de mettre en \u00e9vidence les avanc\u00e9es importantes r\u00e9alis\u00e9es dans le domaine de l\u2019arganiculture, en abordant de mani\u00e8re compl\u00e9mentaire les diff\u00e9rentes \u00e9tapes de production et de domestication de l\u2019arganier.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les r\u00e9sultats des recherches expos\u00e9s ont notamment soulign\u00e9 le r\u00f4le central de la qualit\u00e9 du mat\u00e9riel v\u00e9g\u00e9tal dans la r\u00e9ussite des programmes de plantation, de restauration des \u00e9cosyst\u00e8mes d\u00e9grad\u00e9s et du d\u00e9veloppement d\u2019une arganiculture durable.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lors de cette session, il a \u00e9galement \u00e9t\u00e9 question de mettre en lumi\u00e8re les progr\u00e8s accomplis dans le cadre de la ma\u00eetrise des techniques de production des plants en p\u00e9pini\u00e8re, l\u2019optimisation des conditions de croissance et d\u2019acclimatation des jeunes plants.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Plac\u00e9e sous le Haut Patronage de Sa Majest\u00e9 le Roi Mohammed VI, la 8e \u00e9dition du Congr\u00e8s International de l\u2019Arganier (8-10 mai) r\u00e9unit pr\u00e8s de 500 congressistes, chercheurs, experts, institutionnels et professionnels de la fili\u00e8re, venus du Maroc et de l\u2019\u00e9tranger.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Organis\u00e9 par l\u2019Agence Nationale pour le D\u00e9veloppement des Zones Oasiennes et de l\u2019Arganier (ANDZOA), en partenariat avec l\u2019INRA, l\u2019Agence Nationale des Eaux et For\u00eats (ANEF) et la F\u00e9d\u00e9ration Interprofessionnelle de la Fili\u00e8re de l\u2019Argane (FIFARGANE), cet \u00e9v\u00e9nement d\u2019envergure ambitionne de renforcer les \u00e9changes scientifiques et les partenariats autour du r\u00f4le strat\u00e9gique de l\u2019arganier et de son syst\u00e8me \u00e9cologique, tout en faisant la lumi\u00e8re sur les avanc\u00e9es r\u00e9alis\u00e9es dans les domaines de la recherche, de l\u2019arganiculture et de la valorisation durable des produits d\u00e9riv\u00e9s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dpress L\u2019arganier repr\u00e9sente un levier strat\u00e9gique pour la r\u00e9silience des territoires arides et semi-arides, a soulign\u00e9, dimanche \u00e0 Essaouira, Rachid Mentag, chercheur \u00e0 l\u2019Institut national de la recherche agronomique (INRA). Lors d\u2019un panel organis\u00e9 dans le cadre de la 8e \u00e9dition du Congr\u00e8s International de l\u2019Arganier, sous le th\u00e8me \u201cArganiculture, biotechnologies et am\u00e9lioration g\u00e9n\u00e9tique\u201d, M. &hellip;<\/p>\n","protected":false},"author":2,"featured_media":30632,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[],"class_list":["post-30631","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Essaouira : L\u2019arganier, un levier strat\u00e9gique pour la r\u00e9silience des territoires arides - Dpress.ma\/fr<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dpress.ma\/fr\/2026\/05\/11\/essaouira-larganier-un-levier-strategique-pour-la-resilience-des-territoires-arides\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Essaouira : L\u2019arganier, un levier strat\u00e9gique pour la r\u00e9silience des territoires arides - Dpress.ma\/fr\" \/>\n<meta property=\"og:description\" content=\"Dpress L\u2019arganier repr\u00e9sente un levier strat\u00e9gique pour la r\u00e9silience des territoires arides et semi-arides, a soulign\u00e9, dimanche \u00e0 Essaouira, Rachid Mentag, chercheur \u00e0 l\u2019Institut national de la recherche agronomique (INRA). Lors d\u2019un panel organis\u00e9 dans le cadre de la 8e \u00e9dition du Congr\u00e8s International de l\u2019Arganier, sous le th\u00e8me \u201cArganiculture, biotechnologies et am\u00e9lioration g\u00e9n\u00e9tique\u201d, M. &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dpress.ma\/fr\/2026\/05\/11\/essaouira-larganier-un-levier-strategique-pour-la-resilience-des-territoires-arides\/\" \/>\n<meta property=\"og:site_name\" content=\"Dpress.ma\/fr\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-11T11:07:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-11T11:07:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dpress.ma\/fr\/wp-content\/uploads\/sites\/2\/2026\/05\/62-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2539\" \/>\n\t<meta property=\"og:image:height\" content=\"1594\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dpress.ma\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dpress.ma\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/11\\\/essaouira-larganier-un-levier-strategique-pour-la-resilience-des-territoires-arides\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/11\\\/essaouira-larganier-un-levier-strategique-pour-la-resilience-des-territoires-arides\\\/\"},\"author\":{\"name\":\"Dpress.ma\",\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/#\\\/schema\\\/person\\\/4898febf3ccd59e6578d838656a306a0\"},\"headline\":\"Essaouira : L\u2019arganier, un levier strat\u00e9gique pour la r\u00e9silience des territoires arides\",\"datePublished\":\"2026-05-11T11:07:21+00:00\",\"dateModified\":\"2026-05-11T11:07:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/11\\\/essaouira-larganier-un-levier-strategique-pour-la-resilience-des-territoires-arides\\\/\"},\"wordCount\":455,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/11\\\/essaouira-larganier-un-levier-strategique-pour-la-resilience-des-territoires-arides\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/05\\\/62-3.jpg\",\"articleSection\":[\"\u00c9conomie\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/11\\\/essaouira-larganier-un-levier-strategique-pour-la-resilience-des-territoires-arides\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/11\\\/essaouira-larganier-un-levier-strategique-pour-la-resilience-des-territoires-arides\\\/\",\"url\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/11\\\/essaouira-larganier-un-levier-strategique-pour-la-resilience-des-territoires-arides\\\/\",\"name\":\"Essaouira : L\u2019arganier, un levier strat\u00e9gique pour la r\u00e9silience des territoires arides - Dpress.ma\\\/fr\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/11\\\/essaouira-larganier-un-levier-strategique-pour-la-resilience-des-territoires-arides\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/11\\\/essaouira-larganier-un-levier-strategique-pour-la-resilience-des-territoires-arides\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/05\\\/62-3.jpg\",\"datePublished\":\"2026-05-11T11:07:21+00:00\",\"dateModified\":\"2026-05-11T11:07:25+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/#\\\/schema\\\/person\\\/4898febf3ccd59e6578d838656a306a0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/11\\\/essaouira-larganier-un-levier-strategique-pour-la-resilience-des-territoires-arides\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/11\\\/essaouira-larganier-un-levier-strategique-pour-la-resilience-des-territoires-arides\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/11\\\/essaouira-larganier-un-levier-strategique-pour-la-resilience-des-territoires-arides\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/05\\\/62-3.jpg\",\"contentUrl\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/05\\\/62-3.jpg\",\"width\":2539,\"height\":1594},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/11\\\/essaouira-larganier-un-levier-strategique-pour-la-resilience-des-territoires-arides\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Essaouira : L\u2019arganier, un levier strat\u00e9gique pour la r\u00e9silience des territoires arides\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/\",\"name\":\"Dpress.ma\\\/fr\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/#\\\/schema\\\/person\\\/4898febf3ccd59e6578d838656a306a0\",\"name\":\"Dpress.ma\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72ecc30e9db047a2e0e7176561eb9d564ed77c8108376495b19bd8336405198a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72ecc30e9db047a2e0e7176561eb9d564ed77c8108376495b19bd8336405198a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72ecc30e9db047a2e0e7176561eb9d564ed77c8108376495b19bd8336405198a?s=96&d=mm&r=g\",\"caption\":\"Dpress.ma\"},\"sameAs\":[\"https:\\\/\\\/www.dpress.ma\"],\"url\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/author\\\/dpress-ma\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Essaouira : L\u2019arganier, un levier strat\u00e9gique pour la r\u00e9silience des territoires arides - Dpress.ma\/fr","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dpress.ma\/fr\/2026\/05\/11\/essaouira-larganier-un-levier-strategique-pour-la-resilience-des-territoires-arides\/","og_locale":"fr_FR","og_type":"article","og_title":"Essaouira : L\u2019arganier, un levier strat\u00e9gique pour la r\u00e9silience des territoires arides - Dpress.ma\/fr","og_description":"Dpress L\u2019arganier repr\u00e9sente un levier strat\u00e9gique pour la r\u00e9silience des territoires arides et semi-arides, a soulign\u00e9, dimanche \u00e0 Essaouira, Rachid Mentag, chercheur \u00e0 l\u2019Institut national de la recherche agronomique (INRA). Lors d\u2019un panel organis\u00e9 dans le cadre de la 8e \u00e9dition du Congr\u00e8s International de l\u2019Arganier, sous le th\u00e8me \u201cArganiculture, biotechnologies et am\u00e9lioration g\u00e9n\u00e9tique\u201d, M. &hellip;","og_url":"https:\/\/dpress.ma\/fr\/2026\/05\/11\/essaouira-larganier-un-levier-strategique-pour-la-resilience-des-territoires-arides\/","og_site_name":"Dpress.ma\/fr","article_published_time":"2026-05-11T11:07:21+00:00","article_modified_time":"2026-05-11T11:07:25+00:00","og_image":[{"width":2539,"height":1594,"url":"https:\/\/dpress.ma\/fr\/wp-content\/uploads\/sites\/2\/2026\/05\/62-3.jpg","type":"image\/jpeg"}],"author":"Dpress.ma","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Dpress.ma","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dpress.ma\/fr\/2026\/05\/11\/essaouira-larganier-un-levier-strategique-pour-la-resilience-des-territoires-arides\/#article","isPartOf":{"@id":"https:\/\/dpress.ma\/fr\/2026\/05\/11\/essaouira-larganier-un-levier-strategique-pour-la-resilience-des-territoires-arides\/"},"author":{"name":"Dpress.ma","@id":"https:\/\/dpress.ma\/fr\/#\/schema\/person\/4898febf3ccd59e6578d838656a306a0"},"headline":"Essaouira : L\u2019arganier, un levier strat\u00e9gique pour la r\u00e9silience des territoires arides","datePublished":"2026-05-11T11:07:21+00:00","dateModified":"2026-05-11T11:07:25+00:00","mainEntityOfPage":{"@id":"https:\/\/dpress.ma\/fr\/2026\/05\/11\/essaouira-larganier-un-levier-strategique-pour-la-resilience-des-territoires-arides\/"},"wordCount":455,"commentCount":0,"image":{"@id":"https:\/\/dpress.ma\/fr\/2026\/05\/11\/essaouira-larganier-un-levier-strategique-pour-la-resilience-des-territoires-arides\/#primaryimage"},"thumbnailUrl":"https:\/\/dpress.ma\/fr\/wp-content\/uploads\/sites\/2\/2026\/05\/62-3.jpg","articleSection":["\u00c9conomie"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dpress.ma\/fr\/2026\/05\/11\/essaouira-larganier-un-levier-strategique-pour-la-resilience-des-territoires-arides\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dpress.ma\/fr\/2026\/05\/11\/essaouira-larganier-un-levier-strategique-pour-la-resilience-des-territoires-arides\/","url":"https:\/\/dpress.ma\/fr\/2026\/05\/11\/essaouira-larganier-un-levier-strategique-pour-la-resilience-des-territoires-arides\/","name":"Essaouira : L\u2019arganier, un levier strat\u00e9gique pour la r\u00e9silience des territoires arides - Dpress.ma\/fr","isPartOf":{"@id":"https:\/\/dpress.ma\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dpress.ma\/fr\/2026\/05\/11\/essaouira-larganier-un-levier-strategique-pour-la-resilience-des-territoires-arides\/#primaryimage"},"image":{"@id":"https:\/\/dpress.ma\/fr\/2026\/05\/11\/essaouira-larganier-un-levier-strategique-pour-la-resilience-des-territoires-arides\/#primaryimage"},"thumbnailUrl":"https:\/\/dpress.ma\/fr\/wp-content\/uploads\/sites\/2\/2026\/05\/62-3.jpg","datePublished":"2026-05-11T11:07:21+00:00","dateModified":"2026-05-11T11:07:25+00:00","author":{"@id":"https:\/\/dpress.ma\/fr\/#\/schema\/person\/4898febf3ccd59e6578d838656a306a0"},"breadcrumb":{"@id":"https:\/\/dpress.ma\/fr\/2026\/05\/11\/essaouira-larganier-un-levier-strategique-pour-la-resilience-des-territoires-arides\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dpress.ma\/fr\/2026\/05\/11\/essaouira-larganier-un-levier-strategique-pour-la-resilience-des-territoires-arides\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dpress.ma\/fr\/2026\/05\/11\/essaouira-larganier-un-levier-strategique-pour-la-resilience-des-territoires-arides\/#primaryimage","url":"https:\/\/dpress.ma\/fr\/wp-content\/uploads\/sites\/2\/2026\/05\/62-3.jpg","contentUrl":"https:\/\/dpress.ma\/fr\/wp-content\/uploads\/sites\/2\/2026\/05\/62-3.jpg","width":2539,"height":1594},{"@type":"BreadcrumbList","@id":"https:\/\/dpress.ma\/fr\/2026\/05\/11\/essaouira-larganier-un-levier-strategique-pour-la-resilience-des-territoires-arides\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dpress.ma\/fr\/"},{"@type":"ListItem","position":2,"name":"Essaouira : L\u2019arganier, un levier strat\u00e9gique pour la r\u00e9silience des territoires arides"}]},{"@type":"WebSite","@id":"https:\/\/dpress.ma\/fr\/#website","url":"https:\/\/dpress.ma\/fr\/","name":"Dpress.ma\/fr","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dpress.ma\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/dpress.ma\/fr\/#\/schema\/person\/4898febf3ccd59e6578d838656a306a0","name":"Dpress.ma","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/72ecc30e9db047a2e0e7176561eb9d564ed77c8108376495b19bd8336405198a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/72ecc30e9db047a2e0e7176561eb9d564ed77c8108376495b19bd8336405198a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/72ecc30e9db047a2e0e7176561eb9d564ed77c8108376495b19bd8336405198a?s=96&d=mm&r=g","caption":"Dpress.ma"},"sameAs":["https:\/\/www.dpress.ma"],"url":"https:\/\/dpress.ma\/fr\/author\/dpress-ma\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/posts\/30631","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/comments?post=30631"}],"version-history":[{"count":1,"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/posts\/30631\/revisions"}],"predecessor-version":[{"id":30633,"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/posts\/30631\/revisions\/30633"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/media\/30632"}],"wp:attachment":[{"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/media?parent=30631"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/categories?post=30631"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/tags?post=30631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}