{"id":30607,"date":"2026-05-10T19:38:00","date_gmt":"2026-05-10T19:38:00","guid":{"rendered":"https:\/\/dpress.ma\/fr\/?p=30607"},"modified":"2026-05-10T21:54:49","modified_gmt":"2026-05-10T21:54:49","slug":"la-depouille-de-lun-des-deux-soldats-americains-portes-disparus-a-cap-draa-retrouvee","status":"publish","type":"post","link":"https:\/\/dpress.ma\/fr\/2026\/05\/10\/la-depouille-de-lun-des-deux-soldats-americains-portes-disparus-a-cap-draa-retrouvee\/","title":{"rendered":"La d\u00e9pouille de l\u2019un des deux soldats am\u00e9ricains port\u00e9s disparus \u00e0 Cap Draa retrouv\u00e9e"},"content":{"rendered":"\n<p>Dpress<\/p>\n\n\n\n<p>Les op\u00e9rations de recherche intensives men\u00e9es par les Forces Arm\u00e9es Royales (FAR) conjointement avec les Forces am\u00e9ricaines ont permis de retrouver et rep\u00eacher, le 9 mai 2026, l\u2019un des deux soldats am\u00e9ricains qui participaient \u00e0 l\u2019exercice African Lion 2026, port\u00e9s disparus depuis le 2 mai 2026 au niveau d\u2019une falaise \u00e0 Cap Draa.<\/p>\n\n\n\n<p>Le corps a \u00e9t\u00e9 rep\u00e9r\u00e9 et rep\u00each\u00e9 vers 08H55 par les \u00e9l\u00e9ments des FAR et de la Protection civile suite aux efforts conjugu\u00e9s des \u00e9quipes terrestres, maritimes et a\u00e9riennes. D\u2019apr\u00e8s les premiers \u00e9l\u00e9ments d\u2019enqu\u00eate, il s\u2019agit bien du d\u00e9funt, le Lieutenant Kendrick Lamont Key Jr, indique un communiqu\u00e9 de l\u2019Etat-Major G\u00e9n\u00e9ral des FAR.<\/p>\n\n\n\n<p>La d\u00e9pouille a \u00e9t\u00e9 transf\u00e9r\u00e9e par h\u00e9licopt\u00e8re \u00e0 la morgue de l\u2019H\u00f4pital Militaire Moulay El Hassan \u00e0 Guelmim, conform\u00e9ment \u00e0 la proc\u00e9dure \u00e9tablie, en attendant son rapatriement.<\/p>\n\n\n\n<p>Les op\u00e9rations de recherche et sauvetage se poursuivent pour retrouver le 2\u00e8me militaire am\u00e9ricain, port\u00e9 disparu depuis le 2 mai 2026.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dpress Les op\u00e9rations de recherche intensives men\u00e9es par les Forces Arm\u00e9es Royales (FAR) conjointement avec les Forces am\u00e9ricaines ont permis de retrouver et rep\u00eacher, le 9 mai 2026, l\u2019un des deux soldats am\u00e9ricains qui participaient \u00e0 l\u2019exercice African Lion 2026, port\u00e9s disparus depuis le 2 mai 2026 au niveau d\u2019une falaise \u00e0 Cap Draa. Le &hellip;<\/p>\n","protected":false},"author":2,"featured_media":22710,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[40],"tags":[],"class_list":["post-30607","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-societe-et-regions"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La d\u00e9pouille de l\u2019un des deux soldats am\u00e9ricains port\u00e9s disparus \u00e0 Cap Draa retrouv\u00e9e - Dpress.ma\/fr<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dpress.ma\/fr\/2026\/05\/10\/la-depouille-de-lun-des-deux-soldats-americains-portes-disparus-a-cap-draa-retrouvee\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La d\u00e9pouille de l\u2019un des deux soldats am\u00e9ricains port\u00e9s disparus \u00e0 Cap Draa retrouv\u00e9e - Dpress.ma\/fr\" \/>\n<meta property=\"og:description\" content=\"Dpress Les op\u00e9rations de recherche intensives men\u00e9es par les Forces Arm\u00e9es Royales (FAR) conjointement avec les Forces am\u00e9ricaines ont permis de retrouver et rep\u00eacher, le 9 mai 2026, l\u2019un des deux soldats am\u00e9ricains qui participaient \u00e0 l\u2019exercice African Lion 2026, port\u00e9s disparus depuis le 2 mai 2026 au niveau d\u2019une falaise \u00e0 Cap Draa. Le &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dpress.ma\/fr\/2026\/05\/10\/la-depouille-de-lun-des-deux-soldats-americains-portes-disparus-a-cap-draa-retrouvee\/\" \/>\n<meta property=\"og:site_name\" content=\"Dpress.ma\/fr\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-10T19:38:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-10T21:54:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dpress.ma\/fr\/wp-content\/uploads\/sites\/2\/2026\/01\/MAROC-USA.png\" \/>\n\t<meta property=\"og:image:width\" content=\"780\" \/>\n\t<meta property=\"og:image:height\" content=\"470\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Dpress.ma\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dpress.ma\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/10\\\/la-depouille-de-lun-des-deux-soldats-americains-portes-disparus-a-cap-draa-retrouvee\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/10\\\/la-depouille-de-lun-des-deux-soldats-americains-portes-disparus-a-cap-draa-retrouvee\\\/\"},\"author\":{\"name\":\"Dpress.ma\",\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/#\\\/schema\\\/person\\\/4898febf3ccd59e6578d838656a306a0\"},\"headline\":\"La d\u00e9pouille de l\u2019un des deux soldats am\u00e9ricains port\u00e9s disparus \u00e0 Cap Draa retrouv\u00e9e\",\"datePublished\":\"2026-05-10T19:38:00+00:00\",\"dateModified\":\"2026-05-10T21:54:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/10\\\/la-depouille-de-lun-des-deux-soldats-americains-portes-disparus-a-cap-draa-retrouvee\\\/\"},\"wordCount\":197,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/10\\\/la-depouille-de-lun-des-deux-soldats-americains-portes-disparus-a-cap-draa-retrouvee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/01\\\/MAROC-USA.png\",\"articleSection\":[\"societe et regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/10\\\/la-depouille-de-lun-des-deux-soldats-americains-portes-disparus-a-cap-draa-retrouvee\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/10\\\/la-depouille-de-lun-des-deux-soldats-americains-portes-disparus-a-cap-draa-retrouvee\\\/\",\"url\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/10\\\/la-depouille-de-lun-des-deux-soldats-americains-portes-disparus-a-cap-draa-retrouvee\\\/\",\"name\":\"La d\u00e9pouille de l\u2019un des deux soldats am\u00e9ricains port\u00e9s disparus \u00e0 Cap Draa retrouv\u00e9e - Dpress.ma\\\/fr\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/10\\\/la-depouille-de-lun-des-deux-soldats-americains-portes-disparus-a-cap-draa-retrouvee\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/10\\\/la-depouille-de-lun-des-deux-soldats-americains-portes-disparus-a-cap-draa-retrouvee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/01\\\/MAROC-USA.png\",\"datePublished\":\"2026-05-10T19:38:00+00:00\",\"dateModified\":\"2026-05-10T21:54:49+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/#\\\/schema\\\/person\\\/4898febf3ccd59e6578d838656a306a0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/10\\\/la-depouille-de-lun-des-deux-soldats-americains-portes-disparus-a-cap-draa-retrouvee\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/10\\\/la-depouille-de-lun-des-deux-soldats-americains-portes-disparus-a-cap-draa-retrouvee\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/10\\\/la-depouille-de-lun-des-deux-soldats-americains-portes-disparus-a-cap-draa-retrouvee\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/01\\\/MAROC-USA.png\",\"contentUrl\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/01\\\/MAROC-USA.png\",\"width\":780,\"height\":470},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/2026\\\/05\\\/10\\\/la-depouille-de-lun-des-deux-soldats-americains-portes-disparus-a-cap-draa-retrouvee\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La d\u00e9pouille de l\u2019un des deux soldats am\u00e9ricains port\u00e9s disparus \u00e0 Cap Draa retrouv\u00e9e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/\",\"name\":\"Dpress.ma\\\/fr\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/#\\\/schema\\\/person\\\/4898febf3ccd59e6578d838656a306a0\",\"name\":\"Dpress.ma\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72ecc30e9db047a2e0e7176561eb9d564ed77c8108376495b19bd8336405198a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72ecc30e9db047a2e0e7176561eb9d564ed77c8108376495b19bd8336405198a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72ecc30e9db047a2e0e7176561eb9d564ed77c8108376495b19bd8336405198a?s=96&d=mm&r=g\",\"caption\":\"Dpress.ma\"},\"sameAs\":[\"https:\\\/\\\/www.dpress.ma\"],\"url\":\"https:\\\/\\\/dpress.ma\\\/fr\\\/author\\\/dpress-ma\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La d\u00e9pouille de l\u2019un des deux soldats am\u00e9ricains port\u00e9s disparus \u00e0 Cap Draa retrouv\u00e9e - Dpress.ma\/fr","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dpress.ma\/fr\/2026\/05\/10\/la-depouille-de-lun-des-deux-soldats-americains-portes-disparus-a-cap-draa-retrouvee\/","og_locale":"fr_FR","og_type":"article","og_title":"La d\u00e9pouille de l\u2019un des deux soldats am\u00e9ricains port\u00e9s disparus \u00e0 Cap Draa retrouv\u00e9e - Dpress.ma\/fr","og_description":"Dpress Les op\u00e9rations de recherche intensives men\u00e9es par les Forces Arm\u00e9es Royales (FAR) conjointement avec les Forces am\u00e9ricaines ont permis de retrouver et rep\u00eacher, le 9 mai 2026, l\u2019un des deux soldats am\u00e9ricains qui participaient \u00e0 l\u2019exercice African Lion 2026, port\u00e9s disparus depuis le 2 mai 2026 au niveau d\u2019une falaise \u00e0 Cap Draa. Le &hellip;","og_url":"https:\/\/dpress.ma\/fr\/2026\/05\/10\/la-depouille-de-lun-des-deux-soldats-americains-portes-disparus-a-cap-draa-retrouvee\/","og_site_name":"Dpress.ma\/fr","article_published_time":"2026-05-10T19:38:00+00:00","article_modified_time":"2026-05-10T21:54:49+00:00","og_image":[{"width":780,"height":470,"url":"https:\/\/dpress.ma\/fr\/wp-content\/uploads\/sites\/2\/2026\/01\/MAROC-USA.png","type":"image\/png"}],"author":"Dpress.ma","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Dpress.ma","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dpress.ma\/fr\/2026\/05\/10\/la-depouille-de-lun-des-deux-soldats-americains-portes-disparus-a-cap-draa-retrouvee\/#article","isPartOf":{"@id":"https:\/\/dpress.ma\/fr\/2026\/05\/10\/la-depouille-de-lun-des-deux-soldats-americains-portes-disparus-a-cap-draa-retrouvee\/"},"author":{"name":"Dpress.ma","@id":"https:\/\/dpress.ma\/fr\/#\/schema\/person\/4898febf3ccd59e6578d838656a306a0"},"headline":"La d\u00e9pouille de l\u2019un des deux soldats am\u00e9ricains port\u00e9s disparus \u00e0 Cap Draa retrouv\u00e9e","datePublished":"2026-05-10T19:38:00+00:00","dateModified":"2026-05-10T21:54:49+00:00","mainEntityOfPage":{"@id":"https:\/\/dpress.ma\/fr\/2026\/05\/10\/la-depouille-de-lun-des-deux-soldats-americains-portes-disparus-a-cap-draa-retrouvee\/"},"wordCount":197,"commentCount":0,"image":{"@id":"https:\/\/dpress.ma\/fr\/2026\/05\/10\/la-depouille-de-lun-des-deux-soldats-americains-portes-disparus-a-cap-draa-retrouvee\/#primaryimage"},"thumbnailUrl":"https:\/\/dpress.ma\/fr\/wp-content\/uploads\/sites\/2\/2026\/01\/MAROC-USA.png","articleSection":["societe et regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dpress.ma\/fr\/2026\/05\/10\/la-depouille-de-lun-des-deux-soldats-americains-portes-disparus-a-cap-draa-retrouvee\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dpress.ma\/fr\/2026\/05\/10\/la-depouille-de-lun-des-deux-soldats-americains-portes-disparus-a-cap-draa-retrouvee\/","url":"https:\/\/dpress.ma\/fr\/2026\/05\/10\/la-depouille-de-lun-des-deux-soldats-americains-portes-disparus-a-cap-draa-retrouvee\/","name":"La d\u00e9pouille de l\u2019un des deux soldats am\u00e9ricains port\u00e9s disparus \u00e0 Cap Draa retrouv\u00e9e - Dpress.ma\/fr","isPartOf":{"@id":"https:\/\/dpress.ma\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dpress.ma\/fr\/2026\/05\/10\/la-depouille-de-lun-des-deux-soldats-americains-portes-disparus-a-cap-draa-retrouvee\/#primaryimage"},"image":{"@id":"https:\/\/dpress.ma\/fr\/2026\/05\/10\/la-depouille-de-lun-des-deux-soldats-americains-portes-disparus-a-cap-draa-retrouvee\/#primaryimage"},"thumbnailUrl":"https:\/\/dpress.ma\/fr\/wp-content\/uploads\/sites\/2\/2026\/01\/MAROC-USA.png","datePublished":"2026-05-10T19:38:00+00:00","dateModified":"2026-05-10T21:54:49+00:00","author":{"@id":"https:\/\/dpress.ma\/fr\/#\/schema\/person\/4898febf3ccd59e6578d838656a306a0"},"breadcrumb":{"@id":"https:\/\/dpress.ma\/fr\/2026\/05\/10\/la-depouille-de-lun-des-deux-soldats-americains-portes-disparus-a-cap-draa-retrouvee\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dpress.ma\/fr\/2026\/05\/10\/la-depouille-de-lun-des-deux-soldats-americains-portes-disparus-a-cap-draa-retrouvee\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dpress.ma\/fr\/2026\/05\/10\/la-depouille-de-lun-des-deux-soldats-americains-portes-disparus-a-cap-draa-retrouvee\/#primaryimage","url":"https:\/\/dpress.ma\/fr\/wp-content\/uploads\/sites\/2\/2026\/01\/MAROC-USA.png","contentUrl":"https:\/\/dpress.ma\/fr\/wp-content\/uploads\/sites\/2\/2026\/01\/MAROC-USA.png","width":780,"height":470},{"@type":"BreadcrumbList","@id":"https:\/\/dpress.ma\/fr\/2026\/05\/10\/la-depouille-de-lun-des-deux-soldats-americains-portes-disparus-a-cap-draa-retrouvee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dpress.ma\/fr\/"},{"@type":"ListItem","position":2,"name":"La d\u00e9pouille de l\u2019un des deux soldats am\u00e9ricains port\u00e9s disparus \u00e0 Cap Draa retrouv\u00e9e"}]},{"@type":"WebSite","@id":"https:\/\/dpress.ma\/fr\/#website","url":"https:\/\/dpress.ma\/fr\/","name":"Dpress.ma\/fr","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dpress.ma\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/dpress.ma\/fr\/#\/schema\/person\/4898febf3ccd59e6578d838656a306a0","name":"Dpress.ma","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/72ecc30e9db047a2e0e7176561eb9d564ed77c8108376495b19bd8336405198a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/72ecc30e9db047a2e0e7176561eb9d564ed77c8108376495b19bd8336405198a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/72ecc30e9db047a2e0e7176561eb9d564ed77c8108376495b19bd8336405198a?s=96&d=mm&r=g","caption":"Dpress.ma"},"sameAs":["https:\/\/www.dpress.ma"],"url":"https:\/\/dpress.ma\/fr\/author\/dpress-ma\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/posts\/30607","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/comments?post=30607"}],"version-history":[{"count":1,"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/posts\/30607\/revisions"}],"predecessor-version":[{"id":30608,"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/posts\/30607\/revisions\/30608"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/media\/22710"}],"wp:attachment":[{"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/media?parent=30607"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/categories?post=30607"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dpress.ma\/fr\/wp-json\/wp\/v2\/tags?post=30607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}